{"id":130,"date":"2017-06-06T16:12:10","date_gmt":"2017-06-06T16:12:10","guid":{"rendered":"http:\/\/www.cira.unan.edu.ni\/?p=130"},"modified":"2017-06-06T16:12:10","modified_gmt":"2017-06-06T16:12:10","slug":"personas-expuestas-a-nivel-de-mercurio","status":"publish","type":"post","link":"https:\/\/cira.unan.edu.ni\/index.php\/personas-expuestas-a-nivel-de-mercurio\/","title":{"rendered":"Personas expuestas a nivel de Mercurio"},"content":{"rendered":"<p style=\"text-align: justify;\">En el marco del Proyecto para el Fortalecimiento de Capacidades en el Monitoreo y An\u00e1lisis de Mercurio, que desarrolla la Agencia de Cooperaci\u00f3n Internacional de Jap\u00f3n (JICA) y el Gobierno de la Rep\u00fablica de Nicaragua, se realiz\u00f3 el 2 de febrero el primer muestreo para la colecta de muestras ambientales en el Lago Xolotl\u00e1n, a cargo del Centro para la Investigaci\u00f3n en Recursos Acu\u00e1ticos (CIRA).<\/p>\n<p style=\"text-align: justify;\">El objetivo del proyecto es contribuir a generar informaci\u00f3n cient\u00edfica acerca del estado de contaminaci\u00f3n en el\u00a0 lago Xolotl\u00e1n a causa del Mercurio, en sus diferentes compartimientos: sedimentos, agua y peces.<\/p>\n<p style=\"text-align: justify;\">El muestreo estuvo a cargo Sr. Terumi-Mizuno, Coordinador y Experto del Proyecto\u00a0 y del Dr.\u00a0 Francisco Picado Pav\u00f3n, Director del Laboratorio de Mercurio. Tambi\u00e9n participaron otras instituciones como el Ministerio de Salud (MINSA), el Ministerio del Ambiente y los Recursos Naturales (MARENA) y el Centro para la Investigaci\u00f3n en Recursos Acu\u00e1ticos (CIRA).<\/p>\n<p style=\"text-align: justify;\">Durante el proceso metodol\u00f3gico se realiz\u00f3 capacitaciones humanas para el an\u00e1lisis del Mercurio; seguido se\u00a0 adquiri\u00f3 instrumento\u00a0 anal\u00edtico y por \u00faltimo se ejecut\u00f3 una campa\u00f1a de muestreo para esclarecer la contaminaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">\u00abUna vez que nosotros tengamos los niveles de Mercurio e identifiquemos\u00a0 en el agua los niveles\u00a0 de exposici\u00f3n, a trav\u00e9s del consumo de peces, se va cuantificar\u00a0 los problemas de contaminaci\u00f3n, mediante la implementaci\u00f3n de\u00a0 alternativas que van hacer manejadas a nivel de Gobierno, para eso nosotros contamos con investigaciones propias del CIRA, involucrando al MINSA y al MARENA\u00bb, manifest\u00f3 el Dr.\u00a0 Francisco Picado Pav\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Es de hacer menci\u00f3n, que la Direcci\u00f3n del CIRA propuso esta iniciativa en octubre de 2015, siendo aprobado en febrero de este a\u00f1o. Este proyecto es desarrollado gracias al hermanamiento de la Agencia Internacional Japonesa.<\/p>\n<p style=\"text-align: justify;\">Para la Organizaci\u00f3n Mundial de la Salud (OMS), el Mercurio es uno de los diez productos o grupos de productos qu\u00edmicos que presentan problemas de salud p\u00fablica. La principal v\u00eda de exposici\u00f3n humana es el consumo de pescado y mariscos contaminados con metilmercurio, compuesto org\u00e1nico presente en esos alimentos.<\/p>\n<p style=\"text-align: justify;\">El\u00a0 plan ambiental tiene una duraci\u00f3n de dos a\u00f1os y los resultados van a servir para el desarrollo de un plan de acci\u00f3n, e implementar algunas alternativas de mitigaci\u00f3n contra la contaminaci\u00f3n, localizadas en el lago Xolotl\u00e1n.<\/p>\n<p>&nbsp;<\/p>\n<p>Tomado de la p\u00e1gina Web de la UNAN-Managua<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el marco del Proyecto para el Fortalecimiento de Capacidades en el Monitoreo y An\u00e1lisis de Mercurio, que desarrolla la Agencia de Cooperaci\u00f3n Internacional de Jap\u00f3n (JICA) y el Gobierno de la Rep\u00fablica de Nicaragua, se realiz\u00f3 el 2 de febrero el primer muestreo para la colecta de muestras ambientales en el Lago Xolotl\u00e1n, a cargo del Centro para la Investigaci\u00f3n en Recursos Acu\u00e1ticos (CIRA). El objetivo del proyecto es contribuir a generar informaci\u00f3n cient\u00edfica acerca del estado de contaminaci\u00f3n en el\u00a0 lago Xolotl\u00e1n a causa del Mercurio, en sus diferentes compartimientos: sedimentos, agua y peces. El muestreo estuvo a cargo Sr. Terumi-Mizuno, Coordinador y Experto del Proyecto\u00a0 y del Dr.\u00a0 Francisco Picado Pav\u00f3n, Director del Laboratorio de Mercurio. Tambi\u00e9n participaron otras instituciones como el Ministerio de Salud (MINSA), el Ministerio del Ambiente y los Recursos Naturales (MARENA) y el Centro para la Investigaci\u00f3n en Recursos Acu\u00e1ticos (CIRA). Durante el proceso metodol\u00f3gico se realiz\u00f3 capacitaciones humanas para el an\u00e1lisis del Mercurio; seguido se\u00a0 adquiri\u00f3 instrumento\u00a0 anal\u00edtico y por \u00faltimo se ejecut\u00f3 una campa\u00f1a de muestreo para esclarecer la contaminaci\u00f3n. \u00abUna vez que nosotros tengamos los niveles de Mercurio e identifiquemos\u00a0 en el agua los niveles\u00a0 de exposici\u00f3n, a trav\u00e9s del consumo de peces, se va cuantificar\u00a0 los problemas de contaminaci\u00f3n, mediante la implementaci\u00f3n de\u00a0 alternativas que van hacer manejadas a nivel de Gobierno, para eso nosotros contamos con investigaciones propias del CIRA, involucrando al MINSA y al MARENA\u00bb, manifest\u00f3 el Dr.\u00a0 Francisco Picado Pav\u00f3n. Es de hacer menci\u00f3n, que la Direcci\u00f3n del CIRA propuso esta iniciativa en octubre de 2015, siendo aprobado en febrero de este a\u00f1o. Este proyecto es desarrollado gracias al hermanamiento de la Agencia Internacional Japonesa. Para la Organizaci\u00f3n Mundial de la Salud (OMS), el Mercurio es uno de los diez productos o grupos de productos qu\u00edmicos que presentan problemas de salud p\u00fablica. La principal v\u00eda de exposici\u00f3n humana es el consumo de pescado y mariscos contaminados con metilmercurio, compuesto org\u00e1nico presente en esos alimentos. El\u00a0 plan ambiental tiene una duraci\u00f3n de dos a\u00f1os y los resultados van a servir para el desarrollo de un plan de acci\u00f3n, e implementar algunas alternativas de mitigaci\u00f3n contra la contaminaci\u00f3n, localizadas en el lago Xolotl\u00e1n. &nbsp; Tomado de la p\u00e1gina Web de la UNAN-Managua &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":132,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"wpmdr_menu":1,"wpmdr_menu_extended":{"individualPostRemove":1,"individualPostRemoveDate":1,"individualPostRemoveAuthor":1,"individualPostYoastRemovePublished":1,"individualPostYoastRemoveModified":1},"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-130","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Personas expuestas a nivel de Mercurio - UNAN-Managua\/CIRA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cira.unan.edu.ni\/index.php\/personas-expuestas-a-nivel-de-mercurio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Personas expuestas a nivel de Mercurio - UNAN-Managua\/CIRA\" \/>\n<meta property=\"og:description\" content=\"En el marco del Proyecto para el Fortalecimiento de Capacidades en el Monitoreo y An\u00e1lisis de Mercurio, que desarrolla la Agencia de Cooperaci\u00f3n Internacional de Jap\u00f3n (JICA) y el Gobierno de la Rep\u00fablica de Nicaragua, se realiz\u00f3 el 2 de febrero el primer muestreo para la colecta de muestras ambientales en el Lago Xolotl\u00e1n, a cargo del Centro para la Investigaci\u00f3n en Recursos Acu\u00e1ticos (CIRA). El objetivo del proyecto es contribuir a generar informaci\u00f3n cient\u00edfica acerca del estado de contaminaci\u00f3n en el\u00a0 lago Xolotl\u00e1n a causa del Mercurio, en sus diferentes compartimientos: sedimentos, agua y peces. El muestreo estuvo a cargo Sr. Terumi-Mizuno, Coordinador y Experto del Proyecto\u00a0 y del Dr.\u00a0 Francisco Picado Pav\u00f3n, Director del Laboratorio de Mercurio. Tambi\u00e9n participaron otras instituciones como el Ministerio de Salud (MINSA), el Ministerio del Ambiente y los Recursos Naturales (MARENA) y el Centro para la Investigaci\u00f3n en Recursos Acu\u00e1ticos (CIRA). Durante el proceso metodol\u00f3gico se realiz\u00f3 capacitaciones humanas para el an\u00e1lisis del Mercurio; seguido se\u00a0 adquiri\u00f3 instrumento\u00a0 anal\u00edtico y por \u00faltimo se ejecut\u00f3 una campa\u00f1a de muestreo para esclarecer la contaminaci\u00f3n. \u00abUna vez que nosotros tengamos los niveles de Mercurio e identifiquemos\u00a0 en el agua los niveles\u00a0 de exposici\u00f3n, a trav\u00e9s del consumo de peces, se va cuantificar\u00a0 los problemas de contaminaci\u00f3n, mediante la implementaci\u00f3n de\u00a0 alternativas que van hacer manejadas a nivel de Gobierno, para eso nosotros contamos con investigaciones propias del CIRA, involucrando al MINSA y al MARENA\u00bb, manifest\u00f3 el Dr.\u00a0 Francisco Picado Pav\u00f3n. Es de hacer menci\u00f3n, que la Direcci\u00f3n del CIRA propuso esta iniciativa en octubre de 2015, siendo aprobado en febrero de este a\u00f1o. Este proyecto es desarrollado gracias al hermanamiento de la Agencia Internacional Japonesa. Para la Organizaci\u00f3n Mundial de la Salud (OMS), el Mercurio es uno de los diez productos o grupos de productos qu\u00edmicos que presentan problemas de salud p\u00fablica. La principal v\u00eda de exposici\u00f3n humana es el consumo de pescado y mariscos contaminados con metilmercurio, compuesto org\u00e1nico presente en esos alimentos. El\u00a0 plan ambiental tiene una duraci\u00f3n de dos a\u00f1os y los resultados van a servir para el desarrollo de un plan de acci\u00f3n, e implementar algunas alternativas de mitigaci\u00f3n contra la contaminaci\u00f3n, localizadas en el lago Xolotl\u00e1n. &nbsp; Tomado de la p\u00e1gina Web de la UNAN-Managua &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cira.unan.edu.ni\/index.php\/personas-expuestas-a-nivel-de-mercurio\/\" \/>\n<meta property=\"og:site_name\" content=\"UNAN-Managua\/CIRA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Cira.Unan\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-06T16:12:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/cira.unan.edu.ni\/wp-content\/uploads\/2017\/06\/ciracon.jpg?fit=600%2C348&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"348\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin-cira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CiraUnan\" \/>\n<meta name=\"twitter:site\" content=\"@CiraUnan\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/personas-expuestas-a-nivel-de-mercurio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/personas-expuestas-a-nivel-de-mercurio\\\/\"},\"author\":{\"name\":\"admin-cira\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#\\\/schema\\\/person\\\/ea471033ecfbf0f1297140bb71bc2661\"},\"headline\":\"Personas expuestas a nivel de Mercurio\",\"datePublished\":\"2017-06-06T16:12:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/personas-expuestas-a-nivel-de-mercurio\\\/\"},\"wordCount\":420,\"publisher\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/personas-expuestas-a-nivel-de-mercurio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cira.unan.edu.ni\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/ciracon.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/personas-expuestas-a-nivel-de-mercurio\\\/\",\"url\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/personas-expuestas-a-nivel-de-mercurio\\\/\",\"name\":\"Personas expuestas a nivel de Mercurio - UNAN-Managua\\\/CIRA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/personas-expuestas-a-nivel-de-mercurio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/personas-expuestas-a-nivel-de-mercurio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cira.unan.edu.ni\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/ciracon.jpg\",\"datePublished\":\"2017-06-06T16:12:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/personas-expuestas-a-nivel-de-mercurio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/personas-expuestas-a-nivel-de-mercurio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/personas-expuestas-a-nivel-de-mercurio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cira.unan.edu.ni\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/ciracon.jpg\",\"contentUrl\":\"https:\\\/\\\/cira.unan.edu.ni\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/ciracon.jpg\",\"width\":600,\"height\":348},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/personas-expuestas-a-nivel-de-mercurio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cira.unan.edu.ni\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Personas expuestas a nivel de Mercurio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#website\",\"url\":\"https:\\\/\\\/cira.unan.edu.ni\\\/\",\"name\":\"CIRA\\\/UNAN-Managua\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cira.unan.edu.ni\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#organization\",\"name\":\"CIRA\\\/UNAN-Managua\",\"url\":\"https:\\\/\\\/cira.unan.edu.ni\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cira.unan.edu.ni\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/logo_web_2018.fw_.png\",\"contentUrl\":\"https:\\\/\\\/cira.unan.edu.ni\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/logo_web_2018.fw_.png\",\"width\":413,\"height\":88,\"caption\":\"CIRA\\\/UNAN-Managua\"},\"image\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Cira.Unan\\\/\",\"https:\\\/\\\/x.com\\\/CiraUnan\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/cira-unan-managua-77058327\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCJ6caCqajBqeuhTqIPz5shg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#\\\/schema\\\/person\\\/ea471033ecfbf0f1297140bb71bc2661\",\"name\":\"admin-cira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0760a9b63fc3293644d0450eb8175c0c7d9ddd41708cd3d9ab626d656a9a9876?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0760a9b63fc3293644d0450eb8175c0c7d9ddd41708cd3d9ab626d656a9a9876?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0760a9b63fc3293644d0450eb8175c0c7d9ddd41708cd3d9ab626d656a9a9876?s=96&d=mm&r=g\",\"caption\":\"admin-cira\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Personas expuestas a nivel de Mercurio - UNAN-Managua\/CIRA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cira.unan.edu.ni\/index.php\/personas-expuestas-a-nivel-de-mercurio\/","og_locale":"es_ES","og_type":"article","og_title":"Personas expuestas a nivel de Mercurio - UNAN-Managua\/CIRA","og_description":"En el marco del Proyecto para el Fortalecimiento de Capacidades en el Monitoreo y An\u00e1lisis de Mercurio, que desarrolla la Agencia de Cooperaci\u00f3n Internacional de Jap\u00f3n (JICA) y el Gobierno de la Rep\u00fablica de Nicaragua, se realiz\u00f3 el 2 de febrero el primer muestreo para la colecta de muestras ambientales en el Lago Xolotl\u00e1n, a cargo del Centro para la Investigaci\u00f3n en Recursos Acu\u00e1ticos (CIRA). El objetivo del proyecto es contribuir a generar informaci\u00f3n cient\u00edfica acerca del estado de contaminaci\u00f3n en el\u00a0 lago Xolotl\u00e1n a causa del Mercurio, en sus diferentes compartimientos: sedimentos, agua y peces. El muestreo estuvo a cargo Sr. Terumi-Mizuno, Coordinador y Experto del Proyecto\u00a0 y del Dr.\u00a0 Francisco Picado Pav\u00f3n, Director del Laboratorio de Mercurio. Tambi\u00e9n participaron otras instituciones como el Ministerio de Salud (MINSA), el Ministerio del Ambiente y los Recursos Naturales (MARENA) y el Centro para la Investigaci\u00f3n en Recursos Acu\u00e1ticos (CIRA). Durante el proceso metodol\u00f3gico se realiz\u00f3 capacitaciones humanas para el an\u00e1lisis del Mercurio; seguido se\u00a0 adquiri\u00f3 instrumento\u00a0 anal\u00edtico y por \u00faltimo se ejecut\u00f3 una campa\u00f1a de muestreo para esclarecer la contaminaci\u00f3n. \u00abUna vez que nosotros tengamos los niveles de Mercurio e identifiquemos\u00a0 en el agua los niveles\u00a0 de exposici\u00f3n, a trav\u00e9s del consumo de peces, se va cuantificar\u00a0 los problemas de contaminaci\u00f3n, mediante la implementaci\u00f3n de\u00a0 alternativas que van hacer manejadas a nivel de Gobierno, para eso nosotros contamos con investigaciones propias del CIRA, involucrando al MINSA y al MARENA\u00bb, manifest\u00f3 el Dr.\u00a0 Francisco Picado Pav\u00f3n. Es de hacer menci\u00f3n, que la Direcci\u00f3n del CIRA propuso esta iniciativa en octubre de 2015, siendo aprobado en febrero de este a\u00f1o. Este proyecto es desarrollado gracias al hermanamiento de la Agencia Internacional Japonesa. Para la Organizaci\u00f3n Mundial de la Salud (OMS), el Mercurio es uno de los diez productos o grupos de productos qu\u00edmicos que presentan problemas de salud p\u00fablica. La principal v\u00eda de exposici\u00f3n humana es el consumo de pescado y mariscos contaminados con metilmercurio, compuesto org\u00e1nico presente en esos alimentos. El\u00a0 plan ambiental tiene una duraci\u00f3n de dos a\u00f1os y los resultados van a servir para el desarrollo de un plan de acci\u00f3n, e implementar algunas alternativas de mitigaci\u00f3n contra la contaminaci\u00f3n, localizadas en el lago Xolotl\u00e1n. &nbsp; Tomado de la p\u00e1gina Web de la UNAN-Managua &nbsp;","og_url":"https:\/\/cira.unan.edu.ni\/index.php\/personas-expuestas-a-nivel-de-mercurio\/","og_site_name":"UNAN-Managua\/CIRA","article_publisher":"https:\/\/www.facebook.com\/Cira.Unan\/","article_published_time":"2017-06-06T16:12:10+00:00","og_image":[{"width":600,"height":348,"url":"https:\/\/i0.wp.com\/cira.unan.edu.ni\/wp-content\/uploads\/2017\/06\/ciracon.jpg?fit=600%2C348&ssl=1","type":"image\/jpeg"}],"author":"admin-cira","twitter_card":"summary_large_image","twitter_creator":"@CiraUnan","twitter_site":"@CiraUnan","twitter_misc":{"Escrito por":false,"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cira.unan.edu.ni\/index.php\/personas-expuestas-a-nivel-de-mercurio\/#article","isPartOf":{"@id":"https:\/\/cira.unan.edu.ni\/index.php\/personas-expuestas-a-nivel-de-mercurio\/"},"author":{"name":"admin-cira","@id":"https:\/\/cira.unan.edu.ni\/#\/schema\/person\/ea471033ecfbf0f1297140bb71bc2661"},"headline":"Personas expuestas a nivel de Mercurio","datePublished":"2017-06-06T16:12:10+00:00","mainEntityOfPage":{"@id":"https:\/\/cira.unan.edu.ni\/index.php\/personas-expuestas-a-nivel-de-mercurio\/"},"wordCount":420,"publisher":{"@id":"https:\/\/cira.unan.edu.ni\/#organization"},"image":{"@id":"https:\/\/cira.unan.edu.ni\/index.php\/personas-expuestas-a-nivel-de-mercurio\/#primaryimage"},"thumbnailUrl":"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2017\/06\/ciracon.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cira.unan.edu.ni\/index.php\/personas-expuestas-a-nivel-de-mercurio\/","url":"https:\/\/cira.unan.edu.ni\/index.php\/personas-expuestas-a-nivel-de-mercurio\/","name":"Personas expuestas a nivel de Mercurio - UNAN-Managua\/CIRA","isPartOf":{"@id":"https:\/\/cira.unan.edu.ni\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cira.unan.edu.ni\/index.php\/personas-expuestas-a-nivel-de-mercurio\/#primaryimage"},"image":{"@id":"https:\/\/cira.unan.edu.ni\/index.php\/personas-expuestas-a-nivel-de-mercurio\/#primaryimage"},"thumbnailUrl":"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2017\/06\/ciracon.jpg","datePublished":"2017-06-06T16:12:10+00:00","breadcrumb":{"@id":"https:\/\/cira.unan.edu.ni\/index.php\/personas-expuestas-a-nivel-de-mercurio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cira.unan.edu.ni\/index.php\/personas-expuestas-a-nivel-de-mercurio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cira.unan.edu.ni\/index.php\/personas-expuestas-a-nivel-de-mercurio\/#primaryimage","url":"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2017\/06\/ciracon.jpg","contentUrl":"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2017\/06\/ciracon.jpg","width":600,"height":348},{"@type":"BreadcrumbList","@id":"https:\/\/cira.unan.edu.ni\/index.php\/personas-expuestas-a-nivel-de-mercurio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cira.unan.edu.ni\/"},{"@type":"ListItem","position":2,"name":"Personas expuestas a nivel de Mercurio"}]},{"@type":"WebSite","@id":"https:\/\/cira.unan.edu.ni\/#website","url":"https:\/\/cira.unan.edu.ni\/","name":"CIRA\/UNAN-Managua","description":"","publisher":{"@id":"https:\/\/cira.unan.edu.ni\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cira.unan.edu.ni\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cira.unan.edu.ni\/#organization","name":"CIRA\/UNAN-Managua","url":"https:\/\/cira.unan.edu.ni\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cira.unan.edu.ni\/#\/schema\/logo\/image\/","url":"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/01\/logo_web_2018.fw_.png","contentUrl":"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/01\/logo_web_2018.fw_.png","width":413,"height":88,"caption":"CIRA\/UNAN-Managua"},"image":{"@id":"https:\/\/cira.unan.edu.ni\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Cira.Unan\/","https:\/\/x.com\/CiraUnan","https:\/\/www.linkedin.com\/in\/cira-unan-managua-77058327\/","https:\/\/www.youtube.com\/channel\/UCJ6caCqajBqeuhTqIPz5shg"]},{"@type":"Person","@id":"https:\/\/cira.unan.edu.ni\/#\/schema\/person\/ea471033ecfbf0f1297140bb71bc2661","name":"admin-cira","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0760a9b63fc3293644d0450eb8175c0c7d9ddd41708cd3d9ab626d656a9a9876?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0760a9b63fc3293644d0450eb8175c0c7d9ddd41708cd3d9ab626d656a9a9876?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0760a9b63fc3293644d0450eb8175c0c7d9ddd41708cd3d9ab626d656a9a9876?s=96&d=mm&r=g","caption":"admin-cira"}}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2017\/06\/ciracon.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/posts\/130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/comments?post=130"}],"version-history":[{"count":0,"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/posts\/130\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/media\/132"}],"wp:attachment":[{"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/media?parent=130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/categories?post=130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/tags?post=130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}