{"id":6837,"date":"2018-07-31T23:13:08","date_gmt":"2018-07-31T23:13:08","guid":{"rendered":"http:\/\/www.cira.unan.edu.ni\/?p=6837"},"modified":"2018-07-31T23:13:08","modified_gmt":"2018-07-31T23:13:08","slug":"cira-unan-managua-participo-en-taller-regional-sobre-estrategias-de-monitoreo-y-manejo-de-florecimientos-algales-bentonicos-fabs-organizado-por-oiea-unesco-y-noaa","status":"publish","type":"post","link":"https:\/\/cira.unan.edu.ni\/index.php\/cira-unan-managua-participo-en-taller-regional-sobre-estrategias-de-monitoreo-y-manejo-de-florecimientos-algales-bentonicos-fabs-organizado-por-oiea-unesco-y-noaa\/","title":{"rendered":"CIRA\/UNAN-Managua particip\u00f3 en \u201cTaller regional sobre Estrategias de monitoreo y manejo de Florecimientos Algales Bent\u00f3nicos (FABs)\u201d organizado por OIEA, UNESCO y NOAA."},"content":{"rendered":"<p style=\"text-align: justify;\">9 &nbsp;a 12 de abril, 2018<\/p>\n<p style=\"text-align: justify;\">Se llev\u00f3 a cabo en M\u00f3naco el Taller regional sobre estrategias de monitoreo y manejo de Florecimientos Algales Bent\u00f3nicos (FABs), organizado por el Organismo Internacional de Energ\u00eda At\u00f3mica (OIEA) y el Tratado de Protecci\u00f3n del Medio Ambiente firmado en 1976 entre Francia, M\u00f3naco e Italia (RAMOGE) en colaboraci\u00f3n con el Comit\u00e9 Cient\u00edfico sobre Investigaciones Oce\u00e1nicas-Comisi\u00f3n Oceanogr\u00e1fica Intergubernamental de la UNESCO (IOC-SCOR Global HAB) y la Administraci\u00f3n Nacional Oce\u00e1nica y Atmosf\u00e9rica de los Estados Unidos (NOAA).<\/p>\n<p style=\"text-align: justify;\">El objetivo del taller fue mejorar las habilidades de los participantes en el establecimiento de un programa de monitoreo y evaluaci\u00f3n de riesgo de los florecimientos algales t\u00f3xicos bent\u00f3nicos, enfocado principalmente a la presencia y abundancia del g\u00e9nero <em>Gambierdiscus<\/em>, el cual est\u00e1 asociado con la intoxicaci\u00f3n no bacteriana de peces m\u00e1s com\u00fan en todo el mundo, as\u00ed como a los efectos de <em>Ostreopsis<\/em> que contin\u00faan siendo el principal problema socio-econ\u00f3mico en \u00e1reas como el Mar Mediterr\u00e1neo.&nbsp; A trav\u00e9s de conferencias magistrales por parte de expertos en el tema y conformando grupos de trabajo se analizaron tres cuestionarios referidos a los siguientes t\u00f3picos:<\/p>\n<ol style=\"text-align: justify;\">\n<li>a) Estrategias de muestreo y metodolog\u00eda<\/li>\n<li>b) Monitoreo de recursos marinos, M\u00e9todos para el an\u00e1lisis de toxinas y Manejo de riesgo.<\/li>\n<li>c) Enfermedades asociadas con los florecimientos algales bent\u00f3nicos: vigilancia, manejo y casos de estudio.<\/li>\n<\/ol>\n<p style=\"text-align: justify;\">A este evento concurrieron 60 cient\u00edficos de 30pa\u00edses desarrollados y en v\u00edas de desarrollo pertenecientes a un amplio rango de regiones que participan en los Proyectos de Cooperaci\u00f3n T\u00e9cnica de la <a href=\"https:\/\/www.iaea.org\/es\" target=\"_blank\" rel=\"noopener\">OIEA<\/a> (Am\u00e9rica Latina y El Caribe: RLA 7022, Asia-Pac\u00edfica: RAS 7026, \u00c1frica: RAF 7014 y Europa). Entre ellos: Algeria, Bangladesh, Brasil, Chile, Colombia, Costa Rica, Cuba, El Salvador, Fiji, Guatemala, Indonesia, Kuwait, Malasia, Islas Marshall, Mauritania, M\u00e9xico, Nicaragua, Pakist\u00e1n, Panam\u00e1, Filipinas, Seychelles, Tailandia, T\u00fanez, Uruguay, Venezuela y Vietnam.<\/p>\n<p style=\"text-align: justify;\">Este taller fue importante para el caso particular de los pa\u00edses de Am\u00e9rica Latina y El Caribe que participan en el Proyecto RLA 7022 \u201cFortalecimiento de la vigilancia y respuesta regional para entornos marinos y costeros sostenibles\u201d ya que la implementaci\u00f3n de una sola metodolog\u00eda (Tester <em>et al<\/em>., 2014) en la determinaci\u00f3n de la presencia y abundancia de <em>Gambierdiscus<\/em>, permitir\u00e1 la comparaci\u00f3n de los datos generados, as\u00ed como la identificaci\u00f3n de zonas de riesgo a la salud humana. En representaci\u00f3n del CIRA\/UNAN-Managua como parte del equipo de trabajo del proyecto RLA 7022 asisti\u00f3 la MSc. Ninoska Chow, experta en identificaci\u00f3n de microalgas marinas t\u00f3xicas del Laboratorio de Hidrobiolog\u00eda.<\/p>\n<p style=\"text-align: justify;\">Este taller se llev\u00f3 a cabo dentro de la Semana del oc\u00e9ano (Monaco Ocean Week, 2nd Edition 2018), la cual es un encuentro internacional destinado a la b\u00fasqueda de soluciones para proteger el medio marino, instituido por la Fundaci\u00f3n Pr\u00edncipe Alberto II de M\u00f3naco, en el que se dan cita expertos internacionales, comunidad cient\u00edfica, voluntariado y administraciones p\u00fablicas, que comparten el fin com\u00fan de proteger nuestros mares y oc\u00e9anos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>9 &nbsp;a 12 de abril, 2018 Se llev\u00f3 a cabo en M\u00f3naco el Taller regional sobre estrategias de monitoreo y manejo de Florecimientos Algales Bent\u00f3nicos (FABs), organizado por el Organismo Internacional de Energ\u00eda At\u00f3mica (OIEA) y el Tratado de Protecci\u00f3n del Medio Ambiente firmado en 1976 entre Francia, M\u00f3naco e Italia (RAMOGE) en colaboraci\u00f3n con el Comit\u00e9 Cient\u00edfico sobre Investigaciones Oce\u00e1nicas-Comisi\u00f3n Oceanogr\u00e1fica Intergubernamental de la UNESCO (IOC-SCOR Global HAB) y la Administraci\u00f3n Nacional Oce\u00e1nica y Atmosf\u00e9rica de los Estados Unidos (NOAA). El objetivo del taller fue mejorar las habilidades de los participantes en el establecimiento de un programa de monitoreo y evaluaci\u00f3n de riesgo de los florecimientos algales t\u00f3xicos bent\u00f3nicos, enfocado principalmente a la presencia y abundancia del g\u00e9nero Gambierdiscus, el cual est\u00e1 asociado con la intoxicaci\u00f3n no bacteriana de peces m\u00e1s com\u00fan en todo el mundo, as\u00ed como a los efectos de Ostreopsis que contin\u00faan siendo el principal problema socio-econ\u00f3mico en \u00e1reas como el Mar Mediterr\u00e1neo.&nbsp; A trav\u00e9s de conferencias magistrales por parte de expertos en el tema y conformando grupos de trabajo se analizaron tres cuestionarios referidos a los siguientes t\u00f3picos: a) Estrategias de muestreo y metodolog\u00eda b) Monitoreo de recursos marinos, M\u00e9todos para el an\u00e1lisis de toxinas y Manejo de riesgo. c) Enfermedades asociadas con los florecimientos algales bent\u00f3nicos: vigilancia, manejo y casos de estudio. A este evento concurrieron 60 cient\u00edficos de 30pa\u00edses desarrollados y en v\u00edas de desarrollo pertenecientes a un amplio rango de regiones que participan en los Proyectos de Cooperaci\u00f3n T\u00e9cnica de la OIEA (Am\u00e9rica Latina y El Caribe: RLA 7022, Asia-Pac\u00edfica: RAS 7026, \u00c1frica: RAF 7014 y Europa). Entre ellos: Algeria, Bangladesh, Brasil, Chile, Colombia, Costa Rica, Cuba, El Salvador, Fiji, Guatemala, Indonesia, Kuwait, Malasia, Islas Marshall, Mauritania, M\u00e9xico, Nicaragua, Pakist\u00e1n, Panam\u00e1, Filipinas, Seychelles, Tailandia, T\u00fanez, Uruguay, Venezuela y Vietnam. Este taller fue importante para el caso particular de los pa\u00edses de Am\u00e9rica Latina y El Caribe que participan en el Proyecto RLA 7022 \u201cFortalecimiento de la vigilancia y respuesta regional para entornos marinos y costeros sostenibles\u201d ya que la implementaci\u00f3n de una sola metodolog\u00eda (Tester et al., 2014) en la determinaci\u00f3n de la presencia y abundancia de Gambierdiscus, permitir\u00e1 la comparaci\u00f3n de los datos generados, as\u00ed como la identificaci\u00f3n de zonas de riesgo a la salud humana. En representaci\u00f3n del CIRA\/UNAN-Managua como parte del equipo de trabajo del proyecto RLA 7022 asisti\u00f3 la MSc. Ninoska Chow, experta en identificaci\u00f3n de microalgas marinas t\u00f3xicas del Laboratorio de Hidrobiolog\u00eda. Este taller se llev\u00f3 a cabo dentro de la Semana del oc\u00e9ano (Monaco Ocean Week, 2nd Edition 2018), la cual es un encuentro internacional destinado a la b\u00fasqueda de soluciones para proteger el medio marino, instituido por la Fundaci\u00f3n Pr\u00edncipe Alberto II de M\u00f3naco, en el que se dan cita expertos internacionales, comunidad cient\u00edfica, voluntariado y administraciones p\u00fablicas, que comparten el fin com\u00fan de proteger nuestros mares y oc\u00e9anos.<\/p>\n","protected":false},"author":1,"featured_media":6839,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"wpmdr_menu":1,"wpmdr_menu_extended":{"individualPostRemove":1,"individualPostRemoveDate":1,"individualPostRemoveAuthor":1,"individualPostYoastRemovePublished":1,"individualPostYoastRemoveModified":1},"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[155],"tags":[],"class_list":["post-6837","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CIRA\/UNAN-Managua particip\u00f3 en \u201cTaller regional sobre Estrategias de monitoreo y manejo de Florecimientos Algales Bent\u00f3nicos (FABs)\u201d organizado por OIEA, UNESCO y NOAA. - UNAN-Managua\/CIRA<\/title>\n<meta name=\"description\" content=\"CIRA\/UNAN-Managua particip\u00f3 en \u201cTaller regional sobre Estrategias de monitoreo y manejo de Florecimientos Algales Bent\u00f3nicos (FABs)\u201d organizado por OIEA, UNESCO y NOAA.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cira.unan.edu.ni\/index.php\/cira-unan-managua-participo-en-taller-regional-sobre-estrategias-de-monitoreo-y-manejo-de-florecimientos-algales-bentonicos-fabs-organizado-por-oiea-unesco-y-noaa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CIRA\/UNAN-Managua particip\u00f3 en \u201cTaller regional sobre Estrategias de monitoreo y manejo de Florecimientos Algales Bent\u00f3nicos (FABs)\u201d organizado por OIEA, UNESCO y NOAA. - UNAN-Managua\/CIRA\" \/>\n<meta property=\"og:description\" content=\"CIRA\/UNAN-Managua particip\u00f3 en \u201cTaller regional sobre Estrategias de monitoreo y manejo de Florecimientos Algales Bent\u00f3nicos (FABs)\u201d organizado por OIEA, UNESCO y NOAA.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cira.unan.edu.ni\/index.php\/cira-unan-managua-participo-en-taller-regional-sobre-estrategias-de-monitoreo-y-manejo-de-florecimientos-algales-bentonicos-fabs-organizado-por-oiea-unesco-y-noaa\/\" \/>\n<meta property=\"og:site_name\" content=\"UNAN-Managua\/CIRA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Cira.Unan\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-31T23:13:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/07\/img_1.png?fit=1015%2C571&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1015\" \/>\n\t<meta property=\"og:image:height\" content=\"571\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin-cira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CiraUnan\" \/>\n<meta name=\"twitter:site\" content=\"@CiraUnan\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/cira-unan-managua-participo-en-taller-regional-sobre-estrategias-de-monitoreo-y-manejo-de-florecimientos-algales-bentonicos-fabs-organizado-por-oiea-unesco-y-noaa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/cira-unan-managua-participo-en-taller-regional-sobre-estrategias-de-monitoreo-y-manejo-de-florecimientos-algales-bentonicos-fabs-organizado-por-oiea-unesco-y-noaa\\\/\"},\"author\":{\"name\":\"admin-cira\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#\\\/schema\\\/person\\\/ea471033ecfbf0f1297140bb71bc2661\"},\"headline\":\"CIRA\\\/UNAN-Managua particip\u00f3 en \u201cTaller regional sobre Estrategias de monitoreo y manejo de Florecimientos Algales Bent\u00f3nicos (FABs)\u201d organizado por OIEA, UNESCO y NOAA.\",\"datePublished\":\"2018-07-31T23:13:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/cira-unan-managua-participo-en-taller-regional-sobre-estrategias-de-monitoreo-y-manejo-de-florecimientos-algales-bentonicos-fabs-organizado-por-oiea-unesco-y-noaa\\\/\"},\"wordCount\":549,\"publisher\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/cira-unan-managua-participo-en-taller-regional-sobre-estrategias-de-monitoreo-y-manejo-de-florecimientos-algales-bentonicos-fabs-organizado-por-oiea-unesco-y-noaa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cira.unan.edu.ni\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/img_1.png\",\"articleSection\":[\"Ultimas noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/cira-unan-managua-participo-en-taller-regional-sobre-estrategias-de-monitoreo-y-manejo-de-florecimientos-algales-bentonicos-fabs-organizado-por-oiea-unesco-y-noaa\\\/\",\"url\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/cira-unan-managua-participo-en-taller-regional-sobre-estrategias-de-monitoreo-y-manejo-de-florecimientos-algales-bentonicos-fabs-organizado-por-oiea-unesco-y-noaa\\\/\",\"name\":\"CIRA\\\/UNAN-Managua particip\u00f3 en \u201cTaller regional sobre Estrategias de monitoreo y manejo de Florecimientos Algales Bent\u00f3nicos (FABs)\u201d organizado por OIEA, UNESCO y NOAA. - UNAN-Managua\\\/CIRA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/cira-unan-managua-participo-en-taller-regional-sobre-estrategias-de-monitoreo-y-manejo-de-florecimientos-algales-bentonicos-fabs-organizado-por-oiea-unesco-y-noaa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/cira-unan-managua-participo-en-taller-regional-sobre-estrategias-de-monitoreo-y-manejo-de-florecimientos-algales-bentonicos-fabs-organizado-por-oiea-unesco-y-noaa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cira.unan.edu.ni\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/img_1.png\",\"datePublished\":\"2018-07-31T23:13:08+00:00\",\"description\":\"CIRA\\\/UNAN-Managua particip\u00f3 en \u201cTaller regional sobre Estrategias de monitoreo y manejo de Florecimientos Algales Bent\u00f3nicos (FABs)\u201d organizado por OIEA, UNESCO y NOAA.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/cira-unan-managua-participo-en-taller-regional-sobre-estrategias-de-monitoreo-y-manejo-de-florecimientos-algales-bentonicos-fabs-organizado-por-oiea-unesco-y-noaa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/cira-unan-managua-participo-en-taller-regional-sobre-estrategias-de-monitoreo-y-manejo-de-florecimientos-algales-bentonicos-fabs-organizado-por-oiea-unesco-y-noaa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/cira-unan-managua-participo-en-taller-regional-sobre-estrategias-de-monitoreo-y-manejo-de-florecimientos-algales-bentonicos-fabs-organizado-por-oiea-unesco-y-noaa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cira.unan.edu.ni\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/img_1.png\",\"contentUrl\":\"https:\\\/\\\/cira.unan.edu.ni\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/img_1.png\",\"width\":1015,\"height\":571},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/cira-unan-managua-participo-en-taller-regional-sobre-estrategias-de-monitoreo-y-manejo-de-florecimientos-algales-bentonicos-fabs-organizado-por-oiea-unesco-y-noaa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cira.unan.edu.ni\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CIRA\\\/UNAN-Managua particip\u00f3 en \u201cTaller regional sobre Estrategias de monitoreo y manejo de Florecimientos Algales Bent\u00f3nicos (FABs)\u201d organizado por OIEA, UNESCO y NOAA.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#website\",\"url\":\"https:\\\/\\\/cira.unan.edu.ni\\\/\",\"name\":\"CIRA\\\/UNAN-Managua\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cira.unan.edu.ni\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#organization\",\"name\":\"CIRA\\\/UNAN-Managua\",\"url\":\"https:\\\/\\\/cira.unan.edu.ni\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cira.unan.edu.ni\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/logo_web_2018.fw_.png\",\"contentUrl\":\"https:\\\/\\\/cira.unan.edu.ni\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/logo_web_2018.fw_.png\",\"width\":413,\"height\":88,\"caption\":\"CIRA\\\/UNAN-Managua\"},\"image\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Cira.Unan\\\/\",\"https:\\\/\\\/x.com\\\/CiraUnan\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/cira-unan-managua-77058327\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCJ6caCqajBqeuhTqIPz5shg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#\\\/schema\\\/person\\\/ea471033ecfbf0f1297140bb71bc2661\",\"name\":\"admin-cira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0760a9b63fc3293644d0450eb8175c0c7d9ddd41708cd3d9ab626d656a9a9876?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0760a9b63fc3293644d0450eb8175c0c7d9ddd41708cd3d9ab626d656a9a9876?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0760a9b63fc3293644d0450eb8175c0c7d9ddd41708cd3d9ab626d656a9a9876?s=96&d=mm&r=g\",\"caption\":\"admin-cira\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CIRA\/UNAN-Managua particip\u00f3 en \u201cTaller regional sobre Estrategias de monitoreo y manejo de Florecimientos Algales Bent\u00f3nicos (FABs)\u201d organizado por OIEA, UNESCO y NOAA. - UNAN-Managua\/CIRA","description":"CIRA\/UNAN-Managua particip\u00f3 en \u201cTaller regional sobre Estrategias de monitoreo y manejo de Florecimientos Algales Bent\u00f3nicos (FABs)\u201d organizado por OIEA, UNESCO y NOAA.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cira.unan.edu.ni\/index.php\/cira-unan-managua-participo-en-taller-regional-sobre-estrategias-de-monitoreo-y-manejo-de-florecimientos-algales-bentonicos-fabs-organizado-por-oiea-unesco-y-noaa\/","og_locale":"es_ES","og_type":"article","og_title":"CIRA\/UNAN-Managua particip\u00f3 en \u201cTaller regional sobre Estrategias de monitoreo y manejo de Florecimientos Algales Bent\u00f3nicos (FABs)\u201d organizado por OIEA, UNESCO y NOAA. - UNAN-Managua\/CIRA","og_description":"CIRA\/UNAN-Managua particip\u00f3 en \u201cTaller regional sobre Estrategias de monitoreo y manejo de Florecimientos Algales Bent\u00f3nicos (FABs)\u201d organizado por OIEA, UNESCO y NOAA.","og_url":"https:\/\/cira.unan.edu.ni\/index.php\/cira-unan-managua-participo-en-taller-regional-sobre-estrategias-de-monitoreo-y-manejo-de-florecimientos-algales-bentonicos-fabs-organizado-por-oiea-unesco-y-noaa\/","og_site_name":"UNAN-Managua\/CIRA","article_publisher":"https:\/\/www.facebook.com\/Cira.Unan\/","article_published_time":"2018-07-31T23:13:08+00:00","og_image":[{"width":1015,"height":571,"url":"https:\/\/i0.wp.com\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/07\/img_1.png?fit=1015%2C571&ssl=1","type":"image\/png"}],"author":"admin-cira","twitter_card":"summary_large_image","twitter_creator":"@CiraUnan","twitter_site":"@CiraUnan","twitter_misc":{"Escrito por":false,"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cira.unan.edu.ni\/index.php\/cira-unan-managua-participo-en-taller-regional-sobre-estrategias-de-monitoreo-y-manejo-de-florecimientos-algales-bentonicos-fabs-organizado-por-oiea-unesco-y-noaa\/#article","isPartOf":{"@id":"https:\/\/cira.unan.edu.ni\/index.php\/cira-unan-managua-participo-en-taller-regional-sobre-estrategias-de-monitoreo-y-manejo-de-florecimientos-algales-bentonicos-fabs-organizado-por-oiea-unesco-y-noaa\/"},"author":{"name":"admin-cira","@id":"https:\/\/cira.unan.edu.ni\/#\/schema\/person\/ea471033ecfbf0f1297140bb71bc2661"},"headline":"CIRA\/UNAN-Managua particip\u00f3 en \u201cTaller regional sobre Estrategias de monitoreo y manejo de Florecimientos Algales Bent\u00f3nicos (FABs)\u201d organizado por OIEA, UNESCO y NOAA.","datePublished":"2018-07-31T23:13:08+00:00","mainEntityOfPage":{"@id":"https:\/\/cira.unan.edu.ni\/index.php\/cira-unan-managua-participo-en-taller-regional-sobre-estrategias-de-monitoreo-y-manejo-de-florecimientos-algales-bentonicos-fabs-organizado-por-oiea-unesco-y-noaa\/"},"wordCount":549,"publisher":{"@id":"https:\/\/cira.unan.edu.ni\/#organization"},"image":{"@id":"https:\/\/cira.unan.edu.ni\/index.php\/cira-unan-managua-participo-en-taller-regional-sobre-estrategias-de-monitoreo-y-manejo-de-florecimientos-algales-bentonicos-fabs-organizado-por-oiea-unesco-y-noaa\/#primaryimage"},"thumbnailUrl":"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/07\/img_1.png","articleSection":["Ultimas noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cira.unan.edu.ni\/index.php\/cira-unan-managua-participo-en-taller-regional-sobre-estrategias-de-monitoreo-y-manejo-de-florecimientos-algales-bentonicos-fabs-organizado-por-oiea-unesco-y-noaa\/","url":"https:\/\/cira.unan.edu.ni\/index.php\/cira-unan-managua-participo-en-taller-regional-sobre-estrategias-de-monitoreo-y-manejo-de-florecimientos-algales-bentonicos-fabs-organizado-por-oiea-unesco-y-noaa\/","name":"CIRA\/UNAN-Managua particip\u00f3 en \u201cTaller regional sobre Estrategias de monitoreo y manejo de Florecimientos Algales Bent\u00f3nicos (FABs)\u201d organizado por OIEA, UNESCO y NOAA. - UNAN-Managua\/CIRA","isPartOf":{"@id":"https:\/\/cira.unan.edu.ni\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cira.unan.edu.ni\/index.php\/cira-unan-managua-participo-en-taller-regional-sobre-estrategias-de-monitoreo-y-manejo-de-florecimientos-algales-bentonicos-fabs-organizado-por-oiea-unesco-y-noaa\/#primaryimage"},"image":{"@id":"https:\/\/cira.unan.edu.ni\/index.php\/cira-unan-managua-participo-en-taller-regional-sobre-estrategias-de-monitoreo-y-manejo-de-florecimientos-algales-bentonicos-fabs-organizado-por-oiea-unesco-y-noaa\/#primaryimage"},"thumbnailUrl":"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/07\/img_1.png","datePublished":"2018-07-31T23:13:08+00:00","description":"CIRA\/UNAN-Managua particip\u00f3 en \u201cTaller regional sobre Estrategias de monitoreo y manejo de Florecimientos Algales Bent\u00f3nicos (FABs)\u201d organizado por OIEA, UNESCO y NOAA.","breadcrumb":{"@id":"https:\/\/cira.unan.edu.ni\/index.php\/cira-unan-managua-participo-en-taller-regional-sobre-estrategias-de-monitoreo-y-manejo-de-florecimientos-algales-bentonicos-fabs-organizado-por-oiea-unesco-y-noaa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cira.unan.edu.ni\/index.php\/cira-unan-managua-participo-en-taller-regional-sobre-estrategias-de-monitoreo-y-manejo-de-florecimientos-algales-bentonicos-fabs-organizado-por-oiea-unesco-y-noaa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cira.unan.edu.ni\/index.php\/cira-unan-managua-participo-en-taller-regional-sobre-estrategias-de-monitoreo-y-manejo-de-florecimientos-algales-bentonicos-fabs-organizado-por-oiea-unesco-y-noaa\/#primaryimage","url":"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/07\/img_1.png","contentUrl":"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/07\/img_1.png","width":1015,"height":571},{"@type":"BreadcrumbList","@id":"https:\/\/cira.unan.edu.ni\/index.php\/cira-unan-managua-participo-en-taller-regional-sobre-estrategias-de-monitoreo-y-manejo-de-florecimientos-algales-bentonicos-fabs-organizado-por-oiea-unesco-y-noaa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cira.unan.edu.ni\/"},{"@type":"ListItem","position":2,"name":"CIRA\/UNAN-Managua particip\u00f3 en \u201cTaller regional sobre Estrategias de monitoreo y manejo de Florecimientos Algales Bent\u00f3nicos (FABs)\u201d organizado por OIEA, UNESCO y NOAA."}]},{"@type":"WebSite","@id":"https:\/\/cira.unan.edu.ni\/#website","url":"https:\/\/cira.unan.edu.ni\/","name":"CIRA\/UNAN-Managua","description":"","publisher":{"@id":"https:\/\/cira.unan.edu.ni\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cira.unan.edu.ni\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cira.unan.edu.ni\/#organization","name":"CIRA\/UNAN-Managua","url":"https:\/\/cira.unan.edu.ni\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cira.unan.edu.ni\/#\/schema\/logo\/image\/","url":"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/01\/logo_web_2018.fw_.png","contentUrl":"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/01\/logo_web_2018.fw_.png","width":413,"height":88,"caption":"CIRA\/UNAN-Managua"},"image":{"@id":"https:\/\/cira.unan.edu.ni\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Cira.Unan\/","https:\/\/x.com\/CiraUnan","https:\/\/www.linkedin.com\/in\/cira-unan-managua-77058327\/","https:\/\/www.youtube.com\/channel\/UCJ6caCqajBqeuhTqIPz5shg"]},{"@type":"Person","@id":"https:\/\/cira.unan.edu.ni\/#\/schema\/person\/ea471033ecfbf0f1297140bb71bc2661","name":"admin-cira","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0760a9b63fc3293644d0450eb8175c0c7d9ddd41708cd3d9ab626d656a9a9876?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0760a9b63fc3293644d0450eb8175c0c7d9ddd41708cd3d9ab626d656a9a9876?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0760a9b63fc3293644d0450eb8175c0c7d9ddd41708cd3d9ab626d656a9a9876?s=96&d=mm&r=g","caption":"admin-cira"}}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/07\/img_1.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/posts\/6837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/comments?post=6837"}],"version-history":[{"count":0,"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/posts\/6837\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/media\/6839"}],"wp:attachment":[{"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/media?parent=6837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/categories?post=6837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/tags?post=6837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}