{"id":6960,"date":"2018-10-09T20:40:44","date_gmt":"2018-10-09T20:40:44","guid":{"rendered":"http:\/\/www.cira.unan.edu.ni\/?p=6960"},"modified":"2018-10-10T17:21:55","modified_gmt":"2018-10-10T17:21:55","slug":"seminario-cientifico-no-5-taxonomia-de-foraminiferos","status":"publish","type":"post","link":"https:\/\/cira.unan.edu.ni\/index.php\/seminario-cientifico-no-5-taxonomia-de-foraminiferos\/","title":{"rendered":"Seminario cient\u00edfico No. 5: Taxonom\u00eda de foramin\u00edferos."},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>05&nbsp;de septiembre, 2018<\/strong><\/p>\n<p style=\"text-align: justify;\">Se llev\u00f3&nbsp;a cabo el quinto seminario del a\u00f1o titulado \u201cTaxonom\u00eda de foramin\u00edferos\u201d en las instalaciones del CIRA\/UNAN-Managua a cargo del Lic. Roberto Cano del Laboratorio de Hidrobiolog\u00eda.<\/p>\n<p style=\"text-align: justify;\">El Lic. Cano comparti\u00f3 con el personal del CIRA los conocimientos adquiridos recientemente en el Instituto de Ciencias del mar y limnolog\u00eda de la Universidad Nacional Aut\u00f3noma de M\u00e9xico (UNAM) sobre taxonom\u00eda de foramin\u00edferos.<\/p>\n<p style=\"text-align: justify;\">Los foramin\u00edferos son peque\u00f1os organismos unicelulares que pertenecen al reino de los protistas riz\u00f3podos, hay mayor abundancia en ambientes marinos, aunque tambi\u00e9n hay especies de agua dulce. Se caracterizan por tener un esqueleto o concha constituido por una o m\u00e1s c\u00e1maras interconectadas que fosilizan con relativa facilidad y que al decaer quedan atrapados en los sedimentos. Esta caracter\u00edstica es la que los hace tan \u00fatil en ecolog\u00eda y paleolimnolog\u00eda ya que se pueden usar como testigos o proxies biol\u00f3gicos y ayudar a reconstruir procesos como por ejemplo los cambios del pH en zonas costeras.<\/p>\n<p style=\"text-align: justify;\">Esta capacitaci\u00f3n recibida recientemente por el Lic. Cano form\u00f3 parte del Proyecto Regional latinoamericano RLA 7020 (Establecimiento de la red de observaci\u00f3n para la acidificaci\u00f3n de los oc\u00e9anos y su impacto en el florecimiento de algas t\u00f3xicas, usando t\u00e9cnicas isot\u00f3picas y nucleares) financiado por la Organizaci\u00f3n Internacional de Energ\u00eda At\u00f3mica (OEIA). En la componente de foram\u00edniferos participaron seis pa\u00edses latinoamericanos (Colombia, Costa Rica, Cuba, El Salvador, Nicaragua y M\u00e9xico) de los 14 integrantes del proyecto (Brasil, Chile, M\u00e9xico, El Salvador, Guatemala, Nicaragua, Costa Rica, Panam\u00e1, Colombia, Venezuela, Cuba, Jamaica, Rep\u00fablica Dominicana y Uruguay).<\/p>\nngg_shortcode_0_placeholder\n","protected":false},"excerpt":{"rendered":"<p>05&nbsp;de septiembre, 2018 Se llev\u00f3&nbsp;a cabo el quinto seminario del a\u00f1o titulado \u201cTaxonom\u00eda de foramin\u00edferos\u201d en las instalaciones del CIRA\/UNAN-Managua a cargo del Lic. Roberto Cano del Laboratorio de Hidrobiolog\u00eda. El Lic. Cano comparti\u00f3 con el personal del CIRA los conocimientos adquiridos recientemente en el Instituto de Ciencias del mar y limnolog\u00eda de la Universidad Nacional Aut\u00f3noma de M\u00e9xico (UNAM) sobre taxonom\u00eda de foramin\u00edferos. Los foramin\u00edferos son peque\u00f1os organismos unicelulares que pertenecen al reino de los protistas riz\u00f3podos, hay mayor abundancia en ambientes marinos, aunque tambi\u00e9n hay especies de agua dulce. Se caracterizan por tener un esqueleto o concha constituido por una o m\u00e1s c\u00e1maras interconectadas que fosilizan con relativa facilidad y que al decaer quedan atrapados en los sedimentos. Esta caracter\u00edstica es la que los hace tan \u00fatil en ecolog\u00eda y paleolimnolog\u00eda ya que se pueden usar como testigos o proxies biol\u00f3gicos y ayudar a reconstruir procesos como por ejemplo los cambios del pH en zonas costeras. Esta capacitaci\u00f3n recibida recientemente por el Lic. Cano form\u00f3 parte del Proyecto Regional latinoamericano RLA 7020 (Establecimiento de la red de observaci\u00f3n para la acidificaci\u00f3n de los oc\u00e9anos y su impacto en el florecimiento de algas t\u00f3xicas, usando t\u00e9cnicas isot\u00f3picas y nucleares) financiado por la Organizaci\u00f3n Internacional de Energ\u00eda At\u00f3mica (OEIA). En la componente de foram\u00edniferos participaron seis pa\u00edses latinoamericanos (Colombia, Costa Rica, Cuba, El Salvador, Nicaragua y M\u00e9xico) de los 14 integrantes del proyecto (Brasil, Chile, M\u00e9xico, El Salvador, Guatemala, Nicaragua, Costa Rica, Panam\u00e1, Colombia, Venezuela, Cuba, Jamaica, Rep\u00fablica Dominicana y Uruguay).<\/p>\n","protected":false},"author":1,"featured_media":6970,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"wpmdr_menu":1,"wpmdr_menu_extended":{"individualPostRemove":1,"individualPostRemoveDate":1,"individualPostRemoveAuthor":1,"individualPostYoastRemovePublished":1,"individualPostYoastRemoveModified":1},"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[160,155],"tags":[],"class_list":["post-6960","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seminarios","category-ultimas-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Seminario cient\u00edfico No. 5: Taxonom\u00eda de foramin\u00edferos. - UNAN-Managua\/CIRA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cira.unan.edu.ni\/index.php\/seminario-cientifico-no-5-taxonomia-de-foraminiferos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Seminario cient\u00edfico No. 5: Taxonom\u00eda de foramin\u00edferos. - UNAN-Managua\/CIRA\" \/>\n<meta property=\"og:description\" content=\"05&nbsp;de septiembre, 2018 Se llev\u00f3&nbsp;a cabo el quinto seminario del a\u00f1o titulado \u201cTaxonom\u00eda de foramin\u00edferos\u201d en las instalaciones del CIRA\/UNAN-Managua a cargo del Lic. Roberto Cano del Laboratorio de Hidrobiolog\u00eda. El Lic. Cano comparti\u00f3 con el personal del CIRA los conocimientos adquiridos recientemente en el Instituto de Ciencias del mar y limnolog\u00eda de la Universidad Nacional Aut\u00f3noma de M\u00e9xico (UNAM) sobre taxonom\u00eda de foramin\u00edferos. Los foramin\u00edferos son peque\u00f1os organismos unicelulares que pertenecen al reino de los protistas riz\u00f3podos, hay mayor abundancia en ambientes marinos, aunque tambi\u00e9n hay especies de agua dulce. Se caracterizan por tener un esqueleto o concha constituido por una o m\u00e1s c\u00e1maras interconectadas que fosilizan con relativa facilidad y que al decaer quedan atrapados en los sedimentos. Esta caracter\u00edstica es la que los hace tan \u00fatil en ecolog\u00eda y paleolimnolog\u00eda ya que se pueden usar como testigos o proxies biol\u00f3gicos y ayudar a reconstruir procesos como por ejemplo los cambios del pH en zonas costeras. Esta capacitaci\u00f3n recibida recientemente por el Lic. Cano form\u00f3 parte del Proyecto Regional latinoamericano RLA 7020 (Establecimiento de la red de observaci\u00f3n para la acidificaci\u00f3n de los oc\u00e9anos y su impacto en el florecimiento de algas t\u00f3xicas, usando t\u00e9cnicas isot\u00f3picas y nucleares) financiado por la Organizaci\u00f3n Internacional de Energ\u00eda At\u00f3mica (OEIA). En la componente de foram\u00edniferos participaron seis pa\u00edses latinoamericanos (Colombia, Costa Rica, Cuba, El Salvador, Nicaragua y M\u00e9xico) de los 14 integrantes del proyecto (Brasil, Chile, M\u00e9xico, El Salvador, Guatemala, Nicaragua, Costa Rica, Panam\u00e1, Colombia, Venezuela, Cuba, Jamaica, Rep\u00fablica Dominicana y Uruguay).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cira.unan.edu.ni\/index.php\/seminario-cientifico-no-5-taxonomia-de-foraminiferos\/\" \/>\n<meta property=\"og:site_name\" content=\"UNAN-Managua\/CIRA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Cira.Unan\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-09T20:40:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-10T17:21:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/10\/taxonomia_de_foraminiferos-1.png?fit=900%2C675&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin-cira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CiraUnan\" \/>\n<meta name=\"twitter:site\" content=\"@CiraUnan\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/seminario-cientifico-no-5-taxonomia-de-foraminiferos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/seminario-cientifico-no-5-taxonomia-de-foraminiferos\\\/\"},\"author\":{\"name\":\"admin-cira\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#\\\/schema\\\/person\\\/ea471033ecfbf0f1297140bb71bc2661\"},\"headline\":\"Seminario cient\u00edfico No. 5: Taxonom\u00eda de foramin\u00edferos.\",\"datePublished\":\"2018-10-09T20:40:44+00:00\",\"dateModified\":\"2018-10-10T17:21:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/seminario-cientifico-no-5-taxonomia-de-foraminiferos\\\/\"},\"wordCount\":321,\"publisher\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/seminario-cientifico-no-5-taxonomia-de-foraminiferos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cira.unan.edu.ni\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/taxonomia_de_foraminiferos-1.png\",\"articleSection\":[\"Seminarios\",\"Ultimas noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/seminario-cientifico-no-5-taxonomia-de-foraminiferos\\\/\",\"url\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/seminario-cientifico-no-5-taxonomia-de-foraminiferos\\\/\",\"name\":\"Seminario cient\u00edfico No. 5: Taxonom\u00eda de foramin\u00edferos. - UNAN-Managua\\\/CIRA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/seminario-cientifico-no-5-taxonomia-de-foraminiferos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/seminario-cientifico-no-5-taxonomia-de-foraminiferos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cira.unan.edu.ni\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/taxonomia_de_foraminiferos-1.png\",\"datePublished\":\"2018-10-09T20:40:44+00:00\",\"dateModified\":\"2018-10-10T17:21:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/seminario-cientifico-no-5-taxonomia-de-foraminiferos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/seminario-cientifico-no-5-taxonomia-de-foraminiferos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/seminario-cientifico-no-5-taxonomia-de-foraminiferos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cira.unan.edu.ni\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/taxonomia_de_foraminiferos-1.png\",\"contentUrl\":\"https:\\\/\\\/cira.unan.edu.ni\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/taxonomia_de_foraminiferos-1.png\",\"width\":900,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/seminario-cientifico-no-5-taxonomia-de-foraminiferos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cira.unan.edu.ni\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Seminario cient\u00edfico No. 5: Taxonom\u00eda de foramin\u00edferos.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#website\",\"url\":\"https:\\\/\\\/cira.unan.edu.ni\\\/\",\"name\":\"CIRA\\\/UNAN-Managua\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cira.unan.edu.ni\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#organization\",\"name\":\"CIRA\\\/UNAN-Managua\",\"url\":\"https:\\\/\\\/cira.unan.edu.ni\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cira.unan.edu.ni\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/logo_web_2018.fw_.png\",\"contentUrl\":\"https:\\\/\\\/cira.unan.edu.ni\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/logo_web_2018.fw_.png\",\"width\":413,\"height\":88,\"caption\":\"CIRA\\\/UNAN-Managua\"},\"image\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Cira.Unan\\\/\",\"https:\\\/\\\/x.com\\\/CiraUnan\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/cira-unan-managua-77058327\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCJ6caCqajBqeuhTqIPz5shg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#\\\/schema\\\/person\\\/ea471033ecfbf0f1297140bb71bc2661\",\"name\":\"admin-cira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0760a9b63fc3293644d0450eb8175c0c7d9ddd41708cd3d9ab626d656a9a9876?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0760a9b63fc3293644d0450eb8175c0c7d9ddd41708cd3d9ab626d656a9a9876?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0760a9b63fc3293644d0450eb8175c0c7d9ddd41708cd3d9ab626d656a9a9876?s=96&d=mm&r=g\",\"caption\":\"admin-cira\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Seminario cient\u00edfico No. 5: Taxonom\u00eda de foramin\u00edferos. - UNAN-Managua\/CIRA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cira.unan.edu.ni\/index.php\/seminario-cientifico-no-5-taxonomia-de-foraminiferos\/","og_locale":"es_ES","og_type":"article","og_title":"Seminario cient\u00edfico No. 5: Taxonom\u00eda de foramin\u00edferos. - UNAN-Managua\/CIRA","og_description":"05&nbsp;de septiembre, 2018 Se llev\u00f3&nbsp;a cabo el quinto seminario del a\u00f1o titulado \u201cTaxonom\u00eda de foramin\u00edferos\u201d en las instalaciones del CIRA\/UNAN-Managua a cargo del Lic. Roberto Cano del Laboratorio de Hidrobiolog\u00eda. El Lic. Cano comparti\u00f3 con el personal del CIRA los conocimientos adquiridos recientemente en el Instituto de Ciencias del mar y limnolog\u00eda de la Universidad Nacional Aut\u00f3noma de M\u00e9xico (UNAM) sobre taxonom\u00eda de foramin\u00edferos. Los foramin\u00edferos son peque\u00f1os organismos unicelulares que pertenecen al reino de los protistas riz\u00f3podos, hay mayor abundancia en ambientes marinos, aunque tambi\u00e9n hay especies de agua dulce. Se caracterizan por tener un esqueleto o concha constituido por una o m\u00e1s c\u00e1maras interconectadas que fosilizan con relativa facilidad y que al decaer quedan atrapados en los sedimentos. Esta caracter\u00edstica es la que los hace tan \u00fatil en ecolog\u00eda y paleolimnolog\u00eda ya que se pueden usar como testigos o proxies biol\u00f3gicos y ayudar a reconstruir procesos como por ejemplo los cambios del pH en zonas costeras. Esta capacitaci\u00f3n recibida recientemente por el Lic. Cano form\u00f3 parte del Proyecto Regional latinoamericano RLA 7020 (Establecimiento de la red de observaci\u00f3n para la acidificaci\u00f3n de los oc\u00e9anos y su impacto en el florecimiento de algas t\u00f3xicas, usando t\u00e9cnicas isot\u00f3picas y nucleares) financiado por la Organizaci\u00f3n Internacional de Energ\u00eda At\u00f3mica (OEIA). En la componente de foram\u00edniferos participaron seis pa\u00edses latinoamericanos (Colombia, Costa Rica, Cuba, El Salvador, Nicaragua y M\u00e9xico) de los 14 integrantes del proyecto (Brasil, Chile, M\u00e9xico, El Salvador, Guatemala, Nicaragua, Costa Rica, Panam\u00e1, Colombia, Venezuela, Cuba, Jamaica, Rep\u00fablica Dominicana y Uruguay).","og_url":"https:\/\/cira.unan.edu.ni\/index.php\/seminario-cientifico-no-5-taxonomia-de-foraminiferos\/","og_site_name":"UNAN-Managua\/CIRA","article_publisher":"https:\/\/www.facebook.com\/Cira.Unan\/","article_published_time":"2018-10-09T20:40:44+00:00","article_modified_time":"2018-10-10T17:21:55+00:00","og_image":[{"width":900,"height":675,"url":"https:\/\/i0.wp.com\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/10\/taxonomia_de_foraminiferos-1.png?fit=900%2C675&ssl=1","type":"image\/png"}],"author":"admin-cira","twitter_card":"summary_large_image","twitter_creator":"@CiraUnan","twitter_site":"@CiraUnan","twitter_misc":{"Escrito por":false,"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cira.unan.edu.ni\/index.php\/seminario-cientifico-no-5-taxonomia-de-foraminiferos\/#article","isPartOf":{"@id":"https:\/\/cira.unan.edu.ni\/index.php\/seminario-cientifico-no-5-taxonomia-de-foraminiferos\/"},"author":{"name":"admin-cira","@id":"https:\/\/cira.unan.edu.ni\/#\/schema\/person\/ea471033ecfbf0f1297140bb71bc2661"},"headline":"Seminario cient\u00edfico No. 5: Taxonom\u00eda de foramin\u00edferos.","datePublished":"2018-10-09T20:40:44+00:00","dateModified":"2018-10-10T17:21:55+00:00","mainEntityOfPage":{"@id":"https:\/\/cira.unan.edu.ni\/index.php\/seminario-cientifico-no-5-taxonomia-de-foraminiferos\/"},"wordCount":321,"publisher":{"@id":"https:\/\/cira.unan.edu.ni\/#organization"},"image":{"@id":"https:\/\/cira.unan.edu.ni\/index.php\/seminario-cientifico-no-5-taxonomia-de-foraminiferos\/#primaryimage"},"thumbnailUrl":"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/10\/taxonomia_de_foraminiferos-1.png","articleSection":["Seminarios","Ultimas noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cira.unan.edu.ni\/index.php\/seminario-cientifico-no-5-taxonomia-de-foraminiferos\/","url":"https:\/\/cira.unan.edu.ni\/index.php\/seminario-cientifico-no-5-taxonomia-de-foraminiferos\/","name":"Seminario cient\u00edfico No. 5: Taxonom\u00eda de foramin\u00edferos. - UNAN-Managua\/CIRA","isPartOf":{"@id":"https:\/\/cira.unan.edu.ni\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cira.unan.edu.ni\/index.php\/seminario-cientifico-no-5-taxonomia-de-foraminiferos\/#primaryimage"},"image":{"@id":"https:\/\/cira.unan.edu.ni\/index.php\/seminario-cientifico-no-5-taxonomia-de-foraminiferos\/#primaryimage"},"thumbnailUrl":"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/10\/taxonomia_de_foraminiferos-1.png","datePublished":"2018-10-09T20:40:44+00:00","dateModified":"2018-10-10T17:21:55+00:00","breadcrumb":{"@id":"https:\/\/cira.unan.edu.ni\/index.php\/seminario-cientifico-no-5-taxonomia-de-foraminiferos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cira.unan.edu.ni\/index.php\/seminario-cientifico-no-5-taxonomia-de-foraminiferos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cira.unan.edu.ni\/index.php\/seminario-cientifico-no-5-taxonomia-de-foraminiferos\/#primaryimage","url":"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/10\/taxonomia_de_foraminiferos-1.png","contentUrl":"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/10\/taxonomia_de_foraminiferos-1.png","width":900,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/cira.unan.edu.ni\/index.php\/seminario-cientifico-no-5-taxonomia-de-foraminiferos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cira.unan.edu.ni\/"},{"@type":"ListItem","position":2,"name":"Seminario cient\u00edfico No. 5: Taxonom\u00eda de foramin\u00edferos."}]},{"@type":"WebSite","@id":"https:\/\/cira.unan.edu.ni\/#website","url":"https:\/\/cira.unan.edu.ni\/","name":"CIRA\/UNAN-Managua","description":"","publisher":{"@id":"https:\/\/cira.unan.edu.ni\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cira.unan.edu.ni\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cira.unan.edu.ni\/#organization","name":"CIRA\/UNAN-Managua","url":"https:\/\/cira.unan.edu.ni\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cira.unan.edu.ni\/#\/schema\/logo\/image\/","url":"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/01\/logo_web_2018.fw_.png","contentUrl":"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/01\/logo_web_2018.fw_.png","width":413,"height":88,"caption":"CIRA\/UNAN-Managua"},"image":{"@id":"https:\/\/cira.unan.edu.ni\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Cira.Unan\/","https:\/\/x.com\/CiraUnan","https:\/\/www.linkedin.com\/in\/cira-unan-managua-77058327\/","https:\/\/www.youtube.com\/channel\/UCJ6caCqajBqeuhTqIPz5shg"]},{"@type":"Person","@id":"https:\/\/cira.unan.edu.ni\/#\/schema\/person\/ea471033ecfbf0f1297140bb71bc2661","name":"admin-cira","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0760a9b63fc3293644d0450eb8175c0c7d9ddd41708cd3d9ab626d656a9a9876?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0760a9b63fc3293644d0450eb8175c0c7d9ddd41708cd3d9ab626d656a9a9876?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0760a9b63fc3293644d0450eb8175c0c7d9ddd41708cd3d9ab626d656a9a9876?s=96&d=mm&r=g","caption":"admin-cira"}}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/10\/taxonomia_de_foraminiferos-1.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/posts\/6960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/comments?post=6960"}],"version-history":[{"count":0,"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/posts\/6960\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/media\/6970"}],"wp:attachment":[{"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/media?parent=6960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/categories?post=6960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/tags?post=6960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}