{"id":7007,"date":"2018-10-16T15:14:45","date_gmt":"2018-10-16T15:14:45","guid":{"rendered":"http:\/\/www.cira.unan.edu.ni\/?p=7007"},"modified":"2018-10-16T15:14:45","modified_gmt":"2018-10-16T15:14:45","slug":"seminario-cientifico-n6-base-de-datos-historicas-bdd-de-dos-lagos-tropicales-nicaraguenses-cocibolca-y-masaya-un-insumo-de-apoyo-para-el-ambito-cientifico-y-academico-de-los-inves","status":"publish","type":"post","link":"https:\/\/cira.unan.edu.ni\/index.php\/seminario-cientifico-n6-base-de-datos-historicas-bdd-de-dos-lagos-tropicales-nicaraguenses-cocibolca-y-masaya-un-insumo-de-apoyo-para-el-ambito-cientifico-y-academico-de-los-inves\/","title":{"rendered":"Seminario cient\u00edfico N\u00b06: \u201cBase de datos hist\u00f3ricas (BDD) de dos lagos tropicales nicarag\u00fcenses (Cocibolca y Masaya): un insumo de apoyo para el \u00e1mbito cient\u00edfico y acad\u00e9mico de los investigadores del CIRA\/UNAN-Managua\u201d"},"content":{"rendered":"<p><strong>Septiembre 12, 2018<\/strong><\/p>\n<p>El MSc. Camilo Fuentes Pe\u00f1a, especialista del Laboratorio de Radioqu\u00edmica ambiental y el Lic. Roberto Cano del Laboratorio de Hidrobiolog\u00eda presentaron las bases de datos de aproximadamente 25 a\u00f1os de 68 y 57 par\u00e1metros f\u00edsico-qu\u00edmicos y biol\u00f3gicos de los Lagos Cocibolca y Masaya, respectivamente.<\/p>\n<p>La compilaci\u00f3n de esta informaci\u00f3n hist\u00f3rica de ambos cuerpos de agua en bases de datos se hizo con el prop\u00f3sito de que el personal del CIRA\/UNAN-Managua pueda tener la informaci\u00f3n disponible para fines investigativos.&nbsp; Se dio a conocer su contenido y estructura para facilitar el manejo de los usuarios potenciales, as\u00ed como algunas pautas para la actualizaci\u00f3n agregando nuevos registros (alimentaci\u00f3n de la BDD). La creaci\u00f3n de estas bases de datos se dio por necesidad de compilar la mayor informaci\u00f3n posible de dichos ecosistemas para prepararla para estudio paleolimnol\u00f3gicos ya que ambos colegas forman parte del Grupo de Investigaciones Paleoambientales (PaleoLab) del CIRA\/UNAN-Managua.<\/p>\nngg_shortcode_0_placeholder\n","protected":false},"excerpt":{"rendered":"<p>Septiembre 12, 2018 El MSc. Camilo Fuentes Pe\u00f1a, especialista del Laboratorio de Radioqu\u00edmica ambiental y el Lic. Roberto Cano del Laboratorio de Hidrobiolog\u00eda presentaron las bases de datos de aproximadamente 25 a\u00f1os de 68 y 57 par\u00e1metros f\u00edsico-qu\u00edmicos y biol\u00f3gicos de los Lagos Cocibolca y Masaya, respectivamente. La compilaci\u00f3n de esta informaci\u00f3n hist\u00f3rica de ambos cuerpos de agua en bases de datos se hizo con el prop\u00f3sito de que el personal del CIRA\/UNAN-Managua pueda tener la informaci\u00f3n disponible para fines investigativos.&nbsp; Se dio a conocer su contenido y estructura para facilitar el manejo de los usuarios potenciales, as\u00ed como algunas pautas para la actualizaci\u00f3n agregando nuevos registros (alimentaci\u00f3n de la BDD). La creaci\u00f3n de estas bases de datos se dio por necesidad de compilar la mayor informaci\u00f3n posible de dichos ecosistemas para prepararla para estudio paleolimnol\u00f3gicos ya que ambos colegas forman parte del Grupo de Investigaciones Paleoambientales (PaleoLab) del CIRA\/UNAN-Managua.<\/p>\n","protected":false},"author":1,"featured_media":7009,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"wpmdr_menu":1,"wpmdr_menu_extended":{"individualPostRemove":1,"individualPostRemoveDate":1,"individualPostRemoveAuthor":1,"individualPostYoastRemovePublished":1,"individualPostYoastRemoveModified":1},"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[160,155],"tags":[],"class_list":["post-7007","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seminarios","category-ultimas-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Seminario cient\u00edfico N\u00b06: \u201cBase de datos hist\u00f3ricas (BDD) de dos lagos tropicales nicarag\u00fcenses (Cocibolca y Masaya): un insumo de apoyo para el \u00e1mbito cient\u00edfico y acad\u00e9mico de los investigadores del CIRA\/UNAN-Managua\u201d - UNAN-Managua\/CIRA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cira.unan.edu.ni\/index.php\/seminario-cientifico-n6-base-de-datos-historicas-bdd-de-dos-lagos-tropicales-nicaraguenses-cocibolca-y-masaya-un-insumo-de-apoyo-para-el-ambito-cientifico-y-academico-de-los-inves\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Seminario cient\u00edfico N\u00b06: \u201cBase de datos hist\u00f3ricas (BDD) de dos lagos tropicales nicarag\u00fcenses (Cocibolca y Masaya): un insumo de apoyo para el \u00e1mbito cient\u00edfico y acad\u00e9mico de los investigadores del CIRA\/UNAN-Managua\u201d - UNAN-Managua\/CIRA\" \/>\n<meta property=\"og:description\" content=\"Septiembre 12, 2018 El MSc. Camilo Fuentes Pe\u00f1a, especialista del Laboratorio de Radioqu\u00edmica ambiental y el Lic. Roberto Cano del Laboratorio de Hidrobiolog\u00eda presentaron las bases de datos de aproximadamente 25 a\u00f1os de 68 y 57 par\u00e1metros f\u00edsico-qu\u00edmicos y biol\u00f3gicos de los Lagos Cocibolca y Masaya, respectivamente. La compilaci\u00f3n de esta informaci\u00f3n hist\u00f3rica de ambos cuerpos de agua en bases de datos se hizo con el prop\u00f3sito de que el personal del CIRA\/UNAN-Managua pueda tener la informaci\u00f3n disponible para fines investigativos.&nbsp; Se dio a conocer su contenido y estructura para facilitar el manejo de los usuarios potenciales, as\u00ed como algunas pautas para la actualizaci\u00f3n agregando nuevos registros (alimentaci\u00f3n de la BDD). La creaci\u00f3n de estas bases de datos se dio por necesidad de compilar la mayor informaci\u00f3n posible de dichos ecosistemas para prepararla para estudio paleolimnol\u00f3gicos ya que ambos colegas forman parte del Grupo de Investigaciones Paleoambientales (PaleoLab) del CIRA\/UNAN-Managua.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cira.unan.edu.ni\/index.php\/seminario-cientifico-n6-base-de-datos-historicas-bdd-de-dos-lagos-tropicales-nicaraguenses-cocibolca-y-masaya-un-insumo-de-apoyo-para-el-ambito-cientifico-y-academico-de-los-inves\/\" \/>\n<meta property=\"og:site_name\" content=\"UNAN-Managua\/CIRA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Cira.Unan\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-16T15:14:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/10\/seminario_6-1.png?fit=900%2C675&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin-cira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CiraUnan\" \/>\n<meta name=\"twitter:site\" content=\"@CiraUnan\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/seminario-cientifico-n6-base-de-datos-historicas-bdd-de-dos-lagos-tropicales-nicaraguenses-cocibolca-y-masaya-un-insumo-de-apoyo-para-el-ambito-cientifico-y-academico-de-los-inves\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/seminario-cientifico-n6-base-de-datos-historicas-bdd-de-dos-lagos-tropicales-nicaraguenses-cocibolca-y-masaya-un-insumo-de-apoyo-para-el-ambito-cientifico-y-academico-de-los-inves\\\/\"},\"author\":{\"name\":\"admin-cira\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#\\\/schema\\\/person\\\/ea471033ecfbf0f1297140bb71bc2661\"},\"headline\":\"Seminario cient\u00edfico N\u00b06: \u201cBase de datos hist\u00f3ricas (BDD) de dos lagos tropicales nicarag\u00fcenses (Cocibolca y Masaya): un insumo de apoyo para el \u00e1mbito cient\u00edfico y acad\u00e9mico de los investigadores del CIRA\\\/UNAN-Managua\u201d\",\"datePublished\":\"2018-10-16T15:14:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/seminario-cientifico-n6-base-de-datos-historicas-bdd-de-dos-lagos-tropicales-nicaraguenses-cocibolca-y-masaya-un-insumo-de-apoyo-para-el-ambito-cientifico-y-academico-de-los-inves\\\/\"},\"wordCount\":229,\"publisher\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/seminario-cientifico-n6-base-de-datos-historicas-bdd-de-dos-lagos-tropicales-nicaraguenses-cocibolca-y-masaya-un-insumo-de-apoyo-para-el-ambito-cientifico-y-academico-de-los-inves\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cira.unan.edu.ni\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/seminario_6-1.png\",\"articleSection\":[\"Seminarios\",\"Ultimas noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/seminario-cientifico-n6-base-de-datos-historicas-bdd-de-dos-lagos-tropicales-nicaraguenses-cocibolca-y-masaya-un-insumo-de-apoyo-para-el-ambito-cientifico-y-academico-de-los-inves\\\/\",\"url\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/seminario-cientifico-n6-base-de-datos-historicas-bdd-de-dos-lagos-tropicales-nicaraguenses-cocibolca-y-masaya-un-insumo-de-apoyo-para-el-ambito-cientifico-y-academico-de-los-inves\\\/\",\"name\":\"Seminario cient\u00edfico N\u00b06: \u201cBase de datos hist\u00f3ricas (BDD) de dos lagos tropicales nicarag\u00fcenses (Cocibolca y Masaya): un insumo de apoyo para el \u00e1mbito cient\u00edfico y acad\u00e9mico de los investigadores del CIRA\\\/UNAN-Managua\u201d - UNAN-Managua\\\/CIRA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/seminario-cientifico-n6-base-de-datos-historicas-bdd-de-dos-lagos-tropicales-nicaraguenses-cocibolca-y-masaya-un-insumo-de-apoyo-para-el-ambito-cientifico-y-academico-de-los-inves\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/seminario-cientifico-n6-base-de-datos-historicas-bdd-de-dos-lagos-tropicales-nicaraguenses-cocibolca-y-masaya-un-insumo-de-apoyo-para-el-ambito-cientifico-y-academico-de-los-inves\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cira.unan.edu.ni\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/seminario_6-1.png\",\"datePublished\":\"2018-10-16T15:14:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/seminario-cientifico-n6-base-de-datos-historicas-bdd-de-dos-lagos-tropicales-nicaraguenses-cocibolca-y-masaya-un-insumo-de-apoyo-para-el-ambito-cientifico-y-academico-de-los-inves\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/seminario-cientifico-n6-base-de-datos-historicas-bdd-de-dos-lagos-tropicales-nicaraguenses-cocibolca-y-masaya-un-insumo-de-apoyo-para-el-ambito-cientifico-y-academico-de-los-inves\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/seminario-cientifico-n6-base-de-datos-historicas-bdd-de-dos-lagos-tropicales-nicaraguenses-cocibolca-y-masaya-un-insumo-de-apoyo-para-el-ambito-cientifico-y-academico-de-los-inves\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cira.unan.edu.ni\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/seminario_6-1.png\",\"contentUrl\":\"https:\\\/\\\/cira.unan.edu.ni\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/seminario_6-1.png\",\"width\":900,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/seminario-cientifico-n6-base-de-datos-historicas-bdd-de-dos-lagos-tropicales-nicaraguenses-cocibolca-y-masaya-un-insumo-de-apoyo-para-el-ambito-cientifico-y-academico-de-los-inves\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cira.unan.edu.ni\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Seminario cient\u00edfico N\u00b06: \u201cBase de datos hist\u00f3ricas (BDD) de dos lagos tropicales nicarag\u00fcenses (Cocibolca y Masaya): un insumo de apoyo para el \u00e1mbito cient\u00edfico y acad\u00e9mico de los investigadores del CIRA\\\/UNAN-Managua\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#website\",\"url\":\"https:\\\/\\\/cira.unan.edu.ni\\\/\",\"name\":\"CIRA\\\/UNAN-Managua\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cira.unan.edu.ni\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#organization\",\"name\":\"CIRA\\\/UNAN-Managua\",\"url\":\"https:\\\/\\\/cira.unan.edu.ni\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cira.unan.edu.ni\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/logo_web_2018.fw_.png\",\"contentUrl\":\"https:\\\/\\\/cira.unan.edu.ni\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/logo_web_2018.fw_.png\",\"width\":413,\"height\":88,\"caption\":\"CIRA\\\/UNAN-Managua\"},\"image\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Cira.Unan\\\/\",\"https:\\\/\\\/x.com\\\/CiraUnan\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/cira-unan-managua-77058327\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCJ6caCqajBqeuhTqIPz5shg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#\\\/schema\\\/person\\\/ea471033ecfbf0f1297140bb71bc2661\",\"name\":\"admin-cira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0760a9b63fc3293644d0450eb8175c0c7d9ddd41708cd3d9ab626d656a9a9876?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0760a9b63fc3293644d0450eb8175c0c7d9ddd41708cd3d9ab626d656a9a9876?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0760a9b63fc3293644d0450eb8175c0c7d9ddd41708cd3d9ab626d656a9a9876?s=96&d=mm&r=g\",\"caption\":\"admin-cira\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Seminario cient\u00edfico N\u00b06: \u201cBase de datos hist\u00f3ricas (BDD) de dos lagos tropicales nicarag\u00fcenses (Cocibolca y Masaya): un insumo de apoyo para el \u00e1mbito cient\u00edfico y acad\u00e9mico de los investigadores del CIRA\/UNAN-Managua\u201d - UNAN-Managua\/CIRA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cira.unan.edu.ni\/index.php\/seminario-cientifico-n6-base-de-datos-historicas-bdd-de-dos-lagos-tropicales-nicaraguenses-cocibolca-y-masaya-un-insumo-de-apoyo-para-el-ambito-cientifico-y-academico-de-los-inves\/","og_locale":"es_ES","og_type":"article","og_title":"Seminario cient\u00edfico N\u00b06: \u201cBase de datos hist\u00f3ricas (BDD) de dos lagos tropicales nicarag\u00fcenses (Cocibolca y Masaya): un insumo de apoyo para el \u00e1mbito cient\u00edfico y acad\u00e9mico de los investigadores del CIRA\/UNAN-Managua\u201d - UNAN-Managua\/CIRA","og_description":"Septiembre 12, 2018 El MSc. Camilo Fuentes Pe\u00f1a, especialista del Laboratorio de Radioqu\u00edmica ambiental y el Lic. Roberto Cano del Laboratorio de Hidrobiolog\u00eda presentaron las bases de datos de aproximadamente 25 a\u00f1os de 68 y 57 par\u00e1metros f\u00edsico-qu\u00edmicos y biol\u00f3gicos de los Lagos Cocibolca y Masaya, respectivamente. La compilaci\u00f3n de esta informaci\u00f3n hist\u00f3rica de ambos cuerpos de agua en bases de datos se hizo con el prop\u00f3sito de que el personal del CIRA\/UNAN-Managua pueda tener la informaci\u00f3n disponible para fines investigativos.&nbsp; Se dio a conocer su contenido y estructura para facilitar el manejo de los usuarios potenciales, as\u00ed como algunas pautas para la actualizaci\u00f3n agregando nuevos registros (alimentaci\u00f3n de la BDD). La creaci\u00f3n de estas bases de datos se dio por necesidad de compilar la mayor informaci\u00f3n posible de dichos ecosistemas para prepararla para estudio paleolimnol\u00f3gicos ya que ambos colegas forman parte del Grupo de Investigaciones Paleoambientales (PaleoLab) del CIRA\/UNAN-Managua.","og_url":"https:\/\/cira.unan.edu.ni\/index.php\/seminario-cientifico-n6-base-de-datos-historicas-bdd-de-dos-lagos-tropicales-nicaraguenses-cocibolca-y-masaya-un-insumo-de-apoyo-para-el-ambito-cientifico-y-academico-de-los-inves\/","og_site_name":"UNAN-Managua\/CIRA","article_publisher":"https:\/\/www.facebook.com\/Cira.Unan\/","article_published_time":"2018-10-16T15:14:45+00:00","og_image":[{"width":900,"height":675,"url":"https:\/\/i0.wp.com\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/10\/seminario_6-1.png?fit=900%2C675&ssl=1","type":"image\/png"}],"author":"admin-cira","twitter_card":"summary_large_image","twitter_creator":"@CiraUnan","twitter_site":"@CiraUnan","twitter_misc":{"Escrito por":false,"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cira.unan.edu.ni\/index.php\/seminario-cientifico-n6-base-de-datos-historicas-bdd-de-dos-lagos-tropicales-nicaraguenses-cocibolca-y-masaya-un-insumo-de-apoyo-para-el-ambito-cientifico-y-academico-de-los-inves\/#article","isPartOf":{"@id":"https:\/\/cira.unan.edu.ni\/index.php\/seminario-cientifico-n6-base-de-datos-historicas-bdd-de-dos-lagos-tropicales-nicaraguenses-cocibolca-y-masaya-un-insumo-de-apoyo-para-el-ambito-cientifico-y-academico-de-los-inves\/"},"author":{"name":"admin-cira","@id":"https:\/\/cira.unan.edu.ni\/#\/schema\/person\/ea471033ecfbf0f1297140bb71bc2661"},"headline":"Seminario cient\u00edfico N\u00b06: \u201cBase de datos hist\u00f3ricas (BDD) de dos lagos tropicales nicarag\u00fcenses (Cocibolca y Masaya): un insumo de apoyo para el \u00e1mbito cient\u00edfico y acad\u00e9mico de los investigadores del CIRA\/UNAN-Managua\u201d","datePublished":"2018-10-16T15:14:45+00:00","mainEntityOfPage":{"@id":"https:\/\/cira.unan.edu.ni\/index.php\/seminario-cientifico-n6-base-de-datos-historicas-bdd-de-dos-lagos-tropicales-nicaraguenses-cocibolca-y-masaya-un-insumo-de-apoyo-para-el-ambito-cientifico-y-academico-de-los-inves\/"},"wordCount":229,"publisher":{"@id":"https:\/\/cira.unan.edu.ni\/#organization"},"image":{"@id":"https:\/\/cira.unan.edu.ni\/index.php\/seminario-cientifico-n6-base-de-datos-historicas-bdd-de-dos-lagos-tropicales-nicaraguenses-cocibolca-y-masaya-un-insumo-de-apoyo-para-el-ambito-cientifico-y-academico-de-los-inves\/#primaryimage"},"thumbnailUrl":"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/10\/seminario_6-1.png","articleSection":["Seminarios","Ultimas noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cira.unan.edu.ni\/index.php\/seminario-cientifico-n6-base-de-datos-historicas-bdd-de-dos-lagos-tropicales-nicaraguenses-cocibolca-y-masaya-un-insumo-de-apoyo-para-el-ambito-cientifico-y-academico-de-los-inves\/","url":"https:\/\/cira.unan.edu.ni\/index.php\/seminario-cientifico-n6-base-de-datos-historicas-bdd-de-dos-lagos-tropicales-nicaraguenses-cocibolca-y-masaya-un-insumo-de-apoyo-para-el-ambito-cientifico-y-academico-de-los-inves\/","name":"Seminario cient\u00edfico N\u00b06: \u201cBase de datos hist\u00f3ricas (BDD) de dos lagos tropicales nicarag\u00fcenses (Cocibolca y Masaya): un insumo de apoyo para el \u00e1mbito cient\u00edfico y acad\u00e9mico de los investigadores del CIRA\/UNAN-Managua\u201d - UNAN-Managua\/CIRA","isPartOf":{"@id":"https:\/\/cira.unan.edu.ni\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cira.unan.edu.ni\/index.php\/seminario-cientifico-n6-base-de-datos-historicas-bdd-de-dos-lagos-tropicales-nicaraguenses-cocibolca-y-masaya-un-insumo-de-apoyo-para-el-ambito-cientifico-y-academico-de-los-inves\/#primaryimage"},"image":{"@id":"https:\/\/cira.unan.edu.ni\/index.php\/seminario-cientifico-n6-base-de-datos-historicas-bdd-de-dos-lagos-tropicales-nicaraguenses-cocibolca-y-masaya-un-insumo-de-apoyo-para-el-ambito-cientifico-y-academico-de-los-inves\/#primaryimage"},"thumbnailUrl":"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/10\/seminario_6-1.png","datePublished":"2018-10-16T15:14:45+00:00","breadcrumb":{"@id":"https:\/\/cira.unan.edu.ni\/index.php\/seminario-cientifico-n6-base-de-datos-historicas-bdd-de-dos-lagos-tropicales-nicaraguenses-cocibolca-y-masaya-un-insumo-de-apoyo-para-el-ambito-cientifico-y-academico-de-los-inves\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cira.unan.edu.ni\/index.php\/seminario-cientifico-n6-base-de-datos-historicas-bdd-de-dos-lagos-tropicales-nicaraguenses-cocibolca-y-masaya-un-insumo-de-apoyo-para-el-ambito-cientifico-y-academico-de-los-inves\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cira.unan.edu.ni\/index.php\/seminario-cientifico-n6-base-de-datos-historicas-bdd-de-dos-lagos-tropicales-nicaraguenses-cocibolca-y-masaya-un-insumo-de-apoyo-para-el-ambito-cientifico-y-academico-de-los-inves\/#primaryimage","url":"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/10\/seminario_6-1.png","contentUrl":"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/10\/seminario_6-1.png","width":900,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/cira.unan.edu.ni\/index.php\/seminario-cientifico-n6-base-de-datos-historicas-bdd-de-dos-lagos-tropicales-nicaraguenses-cocibolca-y-masaya-un-insumo-de-apoyo-para-el-ambito-cientifico-y-academico-de-los-inves\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cira.unan.edu.ni\/"},{"@type":"ListItem","position":2,"name":"Seminario cient\u00edfico N\u00b06: \u201cBase de datos hist\u00f3ricas (BDD) de dos lagos tropicales nicarag\u00fcenses (Cocibolca y Masaya): un insumo de apoyo para el \u00e1mbito cient\u00edfico y acad\u00e9mico de los investigadores del CIRA\/UNAN-Managua\u201d"}]},{"@type":"WebSite","@id":"https:\/\/cira.unan.edu.ni\/#website","url":"https:\/\/cira.unan.edu.ni\/","name":"CIRA\/UNAN-Managua","description":"","publisher":{"@id":"https:\/\/cira.unan.edu.ni\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cira.unan.edu.ni\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cira.unan.edu.ni\/#organization","name":"CIRA\/UNAN-Managua","url":"https:\/\/cira.unan.edu.ni\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cira.unan.edu.ni\/#\/schema\/logo\/image\/","url":"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/01\/logo_web_2018.fw_.png","contentUrl":"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/01\/logo_web_2018.fw_.png","width":413,"height":88,"caption":"CIRA\/UNAN-Managua"},"image":{"@id":"https:\/\/cira.unan.edu.ni\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Cira.Unan\/","https:\/\/x.com\/CiraUnan","https:\/\/www.linkedin.com\/in\/cira-unan-managua-77058327\/","https:\/\/www.youtube.com\/channel\/UCJ6caCqajBqeuhTqIPz5shg"]},{"@type":"Person","@id":"https:\/\/cira.unan.edu.ni\/#\/schema\/person\/ea471033ecfbf0f1297140bb71bc2661","name":"admin-cira","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0760a9b63fc3293644d0450eb8175c0c7d9ddd41708cd3d9ab626d656a9a9876?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0760a9b63fc3293644d0450eb8175c0c7d9ddd41708cd3d9ab626d656a9a9876?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0760a9b63fc3293644d0450eb8175c0c7d9ddd41708cd3d9ab626d656a9a9876?s=96&d=mm&r=g","caption":"admin-cira"}}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/10\/seminario_6-1.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/posts\/7007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/comments?post=7007"}],"version-history":[{"count":0,"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/posts\/7007\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/media\/7009"}],"wp:attachment":[{"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/media?parent=7007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/categories?post=7007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/tags?post=7007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}