{"id":7088,"date":"2018-10-26T01:07:59","date_gmt":"2018-10-26T01:07:59","guid":{"rendered":"http:\/\/www.cira.unan.edu.ni\/?p=7088"},"modified":"2025-12-15T11:15:53","modified_gmt":"2025-12-15T17:15:53","slug":"cira-inaugura-sala-de-docentes-investigadores","status":"publish","type":"post","link":"https:\/\/cira.unan.edu.ni\/index.php\/cira-inaugura-sala-de-docentes-investigadores\/","title":{"rendered":"CIRA inaugura Sala de Docentes Investigadores"},"content":{"rendered":"<div class=\"entry-content clearfix\">\n<p style=\"text-align: justify;\">Nuestra Rectora, maestra Ramona Rodr\u00edguez P\u00e9rez, en compa\u00f1\u00eda del Vicerrector General, maestro Jaime L\u00f3pez Lowery;&nbsp; Dra. Maribel Avenda\u00f1o,&nbsp;&nbsp;Vicerrectora de Investigaci\u00f3n y el&nbsp;MSc. Javier Pichardo Ram\u00edrez, Vicerrector de Investigaci\u00f3n saliente,&nbsp;inauguraron en conjunto con las autoridades del Centro para la Investigaci\u00f3n en Recursos Acu\u00e1ticos de Nicaragua (CIRA),&nbsp; la Sala de Docentes Investigadores.<\/p>\n<p style=\"text-align: justify;\">De acuerdo con la MSc. Selvia del Carmen Flores, Directora del Centro, \u00abla infraestructura de la sala era muy antigua, por lo que ameritaba una remodelaci\u00f3n, a fin de que los docentes-investigadores cuenten con un espacio armonioso, saludable y sobre todo bajo el concepto de unidad\u00bb.<\/p>\n<p style=\"text-align: justify;\">Por su parte, la MSc. Ramona Rodr\u00edguez P\u00e9rez, manifest\u00f3 que el CIRA, en medio de todas las dificultades se ha mantenido firme, respondiendo a los compromisos sociales e institucionales. Adem\u00e1s, motiv\u00f3 a los trabajadores docentes y administrativos a ser propositivos, innovadores y emprendedores, manteniendo como eje fundamental el trabajo en equipo.<\/p>\n<p style=\"text-align: justify;\">En esta sala estar\u00e1n ubicados los docentes-investigadores de los laboratorios de Aguas Naturales, Aguas Residuales, Microbiolog\u00eda, Radioqu\u00edmica Ambiental, Contaminantes Org\u00e1nicos y de Contaminantes Met\u00e1licos.<\/p>\n<p style=\"text-align: justify;\">Durante la actividad, las autoridades entregaron placas de reconocimiento a docentes-investigadores jubilados, quienes por muchos a\u00f1os aportaron a la investigaci\u00f3n y al fortalecimiento de la educaci\u00f3n superior nicarag\u00fcense. De igual manera, otorgaron reconocimiento al Dr. Charles Wallace Boudier, exdirector de la Oficina de Relaciones P\u00fablicas y Divulgaci\u00f3n&nbsp; y al Vicerrector de Investigaci\u00f3n saliente, MSc. Javier Pichardo Ram\u00edrez, por su entrega en el fortalecimiento de los procesos educativos acorde con la Misi\u00f3n y Visi\u00f3n Institucional.<\/p>\nngg_shortcode_0_placeholder\n<p style=\"text-align: right;\">Miguel Hondoy<br \/>\nPeriodista de la UNAN-Managua<br \/>\n25\/10\/2018<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nuestra Rectora, maestra Ramona Rodr\u00edguez P\u00e9rez, en compa\u00f1\u00eda del Vicerrector General, maestro Jaime L\u00f3pez Lowery;&nbsp; Dra. Maribel Avenda\u00f1o,&nbsp;&nbsp;Vicerrectora de Investigaci\u00f3n y el&nbsp;MSc. Javier Pichardo Ram\u00edrez, Vicerrector de Investigaci\u00f3n saliente,&nbsp;inauguraron en conjunto con las autoridades del Centro para la Investigaci\u00f3n en Recursos Acu\u00e1ticos de Nicaragua (CIRA),&nbsp; la Sala de Docentes Investigadores. De acuerdo con la MSc. Selvia del Carmen Flores, Directora del Centro, \u00abla infraestructura de la sala era muy antigua, por lo que ameritaba una remodelaci\u00f3n, a fin de que los docentes-investigadores cuenten con un espacio armonioso, saludable y sobre todo bajo el concepto de unidad\u00bb. Por su parte, la MSc. Ramona Rodr\u00edguez P\u00e9rez, manifest\u00f3 que el CIRA, en medio de todas las dificultades se ha mantenido firme, respondiendo a los compromisos sociales e institucionales. Adem\u00e1s, motiv\u00f3 a los trabajadores docentes y administrativos a ser propositivos, innovadores y emprendedores, manteniendo como eje fundamental el trabajo en equipo. En esta sala estar\u00e1n ubicados los docentes-investigadores de los laboratorios de Aguas Naturales, Aguas Residuales, Microbiolog\u00eda, Radioqu\u00edmica Ambiental, Contaminantes Org\u00e1nicos y de Contaminantes Met\u00e1licos. Durante la actividad, las autoridades entregaron placas de reconocimiento a docentes-investigadores jubilados, quienes por muchos a\u00f1os aportaron a la investigaci\u00f3n y al fortalecimiento de la educaci\u00f3n superior nicarag\u00fcense. De igual manera, otorgaron reconocimiento al Dr. Charles Wallace Boudier, exdirector de la Oficina de Relaciones P\u00fablicas y Divulgaci\u00f3n&nbsp; y al Vicerrector de Investigaci\u00f3n saliente, MSc. Javier Pichardo Ram\u00edrez, por su entrega en el fortalecimiento de los procesos educativos acorde con la Misi\u00f3n y Visi\u00f3n Institucional. Miguel Hondoy Periodista de la UNAN-Managua 25\/10\/2018<\/p>\n","protected":false},"author":1,"featured_media":7099,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"wpmdr_menu":0,"wpmdr_menu_extended":{"individualPostRemove":1,"individualPostRemoveDate":1,"individualPostRemoveAuthor":1,"individualPostYoastRemovePublished":1,"individualPostYoastRemoveModified":1},"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[155],"tags":[],"class_list":["post-7088","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CIRA inaugura Sala de Docentes Investigadores - UNAN-Managua\/CIRA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cira.unan.edu.ni\/index.php\/cira-inaugura-sala-de-docentes-investigadores\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CIRA inaugura Sala de Docentes Investigadores - UNAN-Managua\/CIRA\" \/>\n<meta property=\"og:description\" content=\"Nuestra Rectora, maestra Ramona Rodr\u00edguez P\u00e9rez, en compa\u00f1\u00eda del Vicerrector General, maestro Jaime L\u00f3pez Lowery;&nbsp; Dra. Maribel Avenda\u00f1o,&nbsp;&nbsp;Vicerrectora de Investigaci\u00f3n y el&nbsp;MSc. Javier Pichardo Ram\u00edrez, Vicerrector de Investigaci\u00f3n saliente,&nbsp;inauguraron en conjunto con las autoridades del Centro para la Investigaci\u00f3n en Recursos Acu\u00e1ticos de Nicaragua (CIRA),&nbsp; la Sala de Docentes Investigadores. De acuerdo con la MSc. Selvia del Carmen Flores, Directora del Centro, \u00abla infraestructura de la sala era muy antigua, por lo que ameritaba una remodelaci\u00f3n, a fin de que los docentes-investigadores cuenten con un espacio armonioso, saludable y sobre todo bajo el concepto de unidad\u00bb. Por su parte, la MSc. Ramona Rodr\u00edguez P\u00e9rez, manifest\u00f3 que el CIRA, en medio de todas las dificultades se ha mantenido firme, respondiendo a los compromisos sociales e institucionales. Adem\u00e1s, motiv\u00f3 a los trabajadores docentes y administrativos a ser propositivos, innovadores y emprendedores, manteniendo como eje fundamental el trabajo en equipo. En esta sala estar\u00e1n ubicados los docentes-investigadores de los laboratorios de Aguas Naturales, Aguas Residuales, Microbiolog\u00eda, Radioqu\u00edmica Ambiental, Contaminantes Org\u00e1nicos y de Contaminantes Met\u00e1licos. Durante la actividad, las autoridades entregaron placas de reconocimiento a docentes-investigadores jubilados, quienes por muchos a\u00f1os aportaron a la investigaci\u00f3n y al fortalecimiento de la educaci\u00f3n superior nicarag\u00fcense. De igual manera, otorgaron reconocimiento al Dr. Charles Wallace Boudier, exdirector de la Oficina de Relaciones P\u00fablicas y Divulgaci\u00f3n&nbsp; y al Vicerrector de Investigaci\u00f3n saliente, MSc. Javier Pichardo Ram\u00edrez, por su entrega en el fortalecimiento de los procesos educativos acorde con la Misi\u00f3n y Visi\u00f3n Institucional. Miguel Hondoy Periodista de la UNAN-Managua 25\/10\/2018\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cira.unan.edu.ni\/index.php\/cira-inaugura-sala-de-docentes-investigadores\/\" \/>\n<meta property=\"og:site_name\" content=\"UNAN-Managua\/CIRA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Cira.Unan\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-26T01:07:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T17:15:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/10\/SDI.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin-cira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CiraUnan\" \/>\n<meta name=\"twitter:site\" content=\"@CiraUnan\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/cira-inaugura-sala-de-docentes-investigadores\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/cira-inaugura-sala-de-docentes-investigadores\\\/\"},\"author\":{\"name\":\"admin-cira\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#\\\/schema\\\/person\\\/ea471033ecfbf0f1297140bb71bc2661\"},\"headline\":\"CIRA inaugura Sala de Docentes Investigadores\",\"datePublished\":\"2018-10-26T01:07:59+00:00\",\"dateModified\":\"2025-12-15T17:15:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/cira-inaugura-sala-de-docentes-investigadores\\\/\"},\"wordCount\":303,\"publisher\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/cira-inaugura-sala-de-docentes-investigadores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cira.unan.edu.ni\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/SDI.jpg\",\"articleSection\":[\"Ultimas noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/cira-inaugura-sala-de-docentes-investigadores\\\/\",\"url\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/cira-inaugura-sala-de-docentes-investigadores\\\/\",\"name\":\"CIRA inaugura Sala de Docentes Investigadores - UNAN-Managua\\\/CIRA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/cira-inaugura-sala-de-docentes-investigadores\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/cira-inaugura-sala-de-docentes-investigadores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cira.unan.edu.ni\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/SDI.jpg\",\"datePublished\":\"2018-10-26T01:07:59+00:00\",\"dateModified\":\"2025-12-15T17:15:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/cira-inaugura-sala-de-docentes-investigadores\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/cira-inaugura-sala-de-docentes-investigadores\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/cira-inaugura-sala-de-docentes-investigadores\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cira.unan.edu.ni\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/SDI.jpg\",\"contentUrl\":\"https:\\\/\\\/cira.unan.edu.ni\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/SDI.jpg\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/index.php\\\/cira-inaugura-sala-de-docentes-investigadores\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cira.unan.edu.ni\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CIRA inaugura Sala de Docentes Investigadores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#website\",\"url\":\"https:\\\/\\\/cira.unan.edu.ni\\\/\",\"name\":\"CIRA\\\/UNAN-Managua\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cira.unan.edu.ni\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#organization\",\"name\":\"CIRA\\\/UNAN-Managua\",\"url\":\"https:\\\/\\\/cira.unan.edu.ni\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cira.unan.edu.ni\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/logo_web_2018.fw_.png\",\"contentUrl\":\"https:\\\/\\\/cira.unan.edu.ni\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/logo_web_2018.fw_.png\",\"width\":413,\"height\":88,\"caption\":\"CIRA\\\/UNAN-Managua\"},\"image\":{\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Cira.Unan\\\/\",\"https:\\\/\\\/x.com\\\/CiraUnan\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/cira-unan-managua-77058327\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCJ6caCqajBqeuhTqIPz5shg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cira.unan.edu.ni\\\/#\\\/schema\\\/person\\\/ea471033ecfbf0f1297140bb71bc2661\",\"name\":\"admin-cira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0760a9b63fc3293644d0450eb8175c0c7d9ddd41708cd3d9ab626d656a9a9876?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0760a9b63fc3293644d0450eb8175c0c7d9ddd41708cd3d9ab626d656a9a9876?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0760a9b63fc3293644d0450eb8175c0c7d9ddd41708cd3d9ab626d656a9a9876?s=96&d=mm&r=g\",\"caption\":\"admin-cira\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CIRA inaugura Sala de Docentes Investigadores - UNAN-Managua\/CIRA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cira.unan.edu.ni\/index.php\/cira-inaugura-sala-de-docentes-investigadores\/","og_locale":"es_ES","og_type":"article","og_title":"CIRA inaugura Sala de Docentes Investigadores - UNAN-Managua\/CIRA","og_description":"Nuestra Rectora, maestra Ramona Rodr\u00edguez P\u00e9rez, en compa\u00f1\u00eda del Vicerrector General, maestro Jaime L\u00f3pez Lowery;&nbsp; Dra. Maribel Avenda\u00f1o,&nbsp;&nbsp;Vicerrectora de Investigaci\u00f3n y el&nbsp;MSc. Javier Pichardo Ram\u00edrez, Vicerrector de Investigaci\u00f3n saliente,&nbsp;inauguraron en conjunto con las autoridades del Centro para la Investigaci\u00f3n en Recursos Acu\u00e1ticos de Nicaragua (CIRA),&nbsp; la Sala de Docentes Investigadores. De acuerdo con la MSc. Selvia del Carmen Flores, Directora del Centro, \u00abla infraestructura de la sala era muy antigua, por lo que ameritaba una remodelaci\u00f3n, a fin de que los docentes-investigadores cuenten con un espacio armonioso, saludable y sobre todo bajo el concepto de unidad\u00bb. Por su parte, la MSc. Ramona Rodr\u00edguez P\u00e9rez, manifest\u00f3 que el CIRA, en medio de todas las dificultades se ha mantenido firme, respondiendo a los compromisos sociales e institucionales. Adem\u00e1s, motiv\u00f3 a los trabajadores docentes y administrativos a ser propositivos, innovadores y emprendedores, manteniendo como eje fundamental el trabajo en equipo. En esta sala estar\u00e1n ubicados los docentes-investigadores de los laboratorios de Aguas Naturales, Aguas Residuales, Microbiolog\u00eda, Radioqu\u00edmica Ambiental, Contaminantes Org\u00e1nicos y de Contaminantes Met\u00e1licos. Durante la actividad, las autoridades entregaron placas de reconocimiento a docentes-investigadores jubilados, quienes por muchos a\u00f1os aportaron a la investigaci\u00f3n y al fortalecimiento de la educaci\u00f3n superior nicarag\u00fcense. De igual manera, otorgaron reconocimiento al Dr. Charles Wallace Boudier, exdirector de la Oficina de Relaciones P\u00fablicas y Divulgaci\u00f3n&nbsp; y al Vicerrector de Investigaci\u00f3n saliente, MSc. Javier Pichardo Ram\u00edrez, por su entrega en el fortalecimiento de los procesos educativos acorde con la Misi\u00f3n y Visi\u00f3n Institucional. Miguel Hondoy Periodista de la UNAN-Managua 25\/10\/2018","og_url":"https:\/\/cira.unan.edu.ni\/index.php\/cira-inaugura-sala-de-docentes-investigadores\/","og_site_name":"UNAN-Managua\/CIRA","article_publisher":"https:\/\/www.facebook.com\/Cira.Unan\/","article_published_time":"2018-10-26T01:07:59+00:00","article_modified_time":"2025-12-15T17:15:53+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/10\/SDI.jpg","type":"image\/jpeg"}],"author":"admin-cira","twitter_card":"summary_large_image","twitter_creator":"@CiraUnan","twitter_site":"@CiraUnan","twitter_misc":{"Escrito por":false,"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cira.unan.edu.ni\/index.php\/cira-inaugura-sala-de-docentes-investigadores\/#article","isPartOf":{"@id":"https:\/\/cira.unan.edu.ni\/index.php\/cira-inaugura-sala-de-docentes-investigadores\/"},"author":{"name":"admin-cira","@id":"https:\/\/cira.unan.edu.ni\/#\/schema\/person\/ea471033ecfbf0f1297140bb71bc2661"},"headline":"CIRA inaugura Sala de Docentes Investigadores","datePublished":"2018-10-26T01:07:59+00:00","dateModified":"2025-12-15T17:15:53+00:00","mainEntityOfPage":{"@id":"https:\/\/cira.unan.edu.ni\/index.php\/cira-inaugura-sala-de-docentes-investigadores\/"},"wordCount":303,"publisher":{"@id":"https:\/\/cira.unan.edu.ni\/#organization"},"image":{"@id":"https:\/\/cira.unan.edu.ni\/index.php\/cira-inaugura-sala-de-docentes-investigadores\/#primaryimage"},"thumbnailUrl":"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/10\/SDI.jpg","articleSection":["Ultimas noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cira.unan.edu.ni\/index.php\/cira-inaugura-sala-de-docentes-investigadores\/","url":"https:\/\/cira.unan.edu.ni\/index.php\/cira-inaugura-sala-de-docentes-investigadores\/","name":"CIRA inaugura Sala de Docentes Investigadores - UNAN-Managua\/CIRA","isPartOf":{"@id":"https:\/\/cira.unan.edu.ni\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cira.unan.edu.ni\/index.php\/cira-inaugura-sala-de-docentes-investigadores\/#primaryimage"},"image":{"@id":"https:\/\/cira.unan.edu.ni\/index.php\/cira-inaugura-sala-de-docentes-investigadores\/#primaryimage"},"thumbnailUrl":"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/10\/SDI.jpg","datePublished":"2018-10-26T01:07:59+00:00","dateModified":"2025-12-15T17:15:53+00:00","breadcrumb":{"@id":"https:\/\/cira.unan.edu.ni\/index.php\/cira-inaugura-sala-de-docentes-investigadores\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cira.unan.edu.ni\/index.php\/cira-inaugura-sala-de-docentes-investigadores\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cira.unan.edu.ni\/index.php\/cira-inaugura-sala-de-docentes-investigadores\/#primaryimage","url":"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/10\/SDI.jpg","contentUrl":"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/10\/SDI.jpg","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/cira.unan.edu.ni\/index.php\/cira-inaugura-sala-de-docentes-investigadores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cira.unan.edu.ni\/"},{"@type":"ListItem","position":2,"name":"CIRA inaugura Sala de Docentes Investigadores"}]},{"@type":"WebSite","@id":"https:\/\/cira.unan.edu.ni\/#website","url":"https:\/\/cira.unan.edu.ni\/","name":"CIRA\/UNAN-Managua","description":"","publisher":{"@id":"https:\/\/cira.unan.edu.ni\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cira.unan.edu.ni\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cira.unan.edu.ni\/#organization","name":"CIRA\/UNAN-Managua","url":"https:\/\/cira.unan.edu.ni\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cira.unan.edu.ni\/#\/schema\/logo\/image\/","url":"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/01\/logo_web_2018.fw_.png","contentUrl":"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/01\/logo_web_2018.fw_.png","width":413,"height":88,"caption":"CIRA\/UNAN-Managua"},"image":{"@id":"https:\/\/cira.unan.edu.ni\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Cira.Unan\/","https:\/\/x.com\/CiraUnan","https:\/\/www.linkedin.com\/in\/cira-unan-managua-77058327\/","https:\/\/www.youtube.com\/channel\/UCJ6caCqajBqeuhTqIPz5shg"]},{"@type":"Person","@id":"https:\/\/cira.unan.edu.ni\/#\/schema\/person\/ea471033ecfbf0f1297140bb71bc2661","name":"admin-cira","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0760a9b63fc3293644d0450eb8175c0c7d9ddd41708cd3d9ab626d656a9a9876?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0760a9b63fc3293644d0450eb8175c0c7d9ddd41708cd3d9ab626d656a9a9876?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0760a9b63fc3293644d0450eb8175c0c7d9ddd41708cd3d9ab626d656a9a9876?s=96&d=mm&r=g","caption":"admin-cira"}}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/cira.unan.edu.ni\/wp-content\/uploads\/2018\/10\/SDI.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/posts\/7088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/comments?post=7088"}],"version-history":[{"count":2,"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/posts\/7088\/revisions"}],"predecessor-version":[{"id":19831,"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/posts\/7088\/revisions\/19831"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/media\/7099"}],"wp:attachment":[{"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/media?parent=7088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/categories?post=7088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cira.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/tags?post=7088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}